{"id":1553,"date":"2019-11-14T13:39:10","date_gmt":"2019-11-14T13:39:10","guid":{"rendered":"https:\/\/sidimurcia.org\/?p=1553"},"modified":"2019-11-14T13:39:10","modified_gmt":"2019-11-14T13:39:10","slug":"14-11-19-relacion-excluidos-cuerpo-de-maestros-por-no-participar-en-acto-interinos-del-13-11-19","status":"publish","type":"post","link":"https:\/\/sidimurcia.org\/index.php\/2019\/11\/14\/14-11-19-relacion-excluidos-cuerpo-de-maestros-por-no-participar-en-acto-interinos-del-13-11-19\/","title":{"rendered":"14\/11\/19 Relaci\u00f3n EXCLUIDOS Cuerpo de Maestros por no participar en acto interinos del 13\/11\/19"},"content":{"rendered":"<ul>\n<li style=\"text-align: justify;\"><a title=\"14\/11\/2019. Celebrado el acto de adjudicaci\u00f3n el d\u00eda 13 de noviembre de 2019 para cubrir plazas en r\u00e9gimen de interinidad del Cuerpo de Maestros de Infantil y Primaria, se relacionan a continuaci\u00f3n los\/as aspirantes que estando convocados\/as han sido excluidos por no participar en el mismo\" href=\"https:\/\/www.carm.es\/web\/integra.servlets.Blob?ARCHIVO=No%20presentados%20acto%2013-11-2019.doc.pdf&amp;TABLA=ARCHIVOS&amp;CAMPOCLAVE=IDARCHIVO&amp;VALORCLAVE=159476&amp;CAMPOIMAGEN=ARCHIVO&amp;IDTIPO=60&amp;RASTRO=c77$m22725,22759,4254\">14\/11\/2019. Celebrado el acto de adjudicaci\u00f3n el d\u00eda 13 de noviembre de 2019 para cubrir plazas en r\u00e9gimen de interinidad del Cuerpo de Maestros de Infantil y Primaria, se relacionan a continuaci\u00f3n los\/as aspirantes que estando convocados\/as han sido excluidos por no participar en el mismo<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>14\/11\/2019. Celebrado el acto de adjudicaci\u00f3n el d\u00eda 13 de noviembre de 2019 para cubrir plazas en r\u00e9gimen de interinidad &#8230; <a title=\"14\/11\/19 Relaci\u00f3n EXCLUIDOS Cuerpo de Maestros por no participar en acto interinos del 13\/11\/19\" class=\"read-more\" href=\"https:\/\/sidimurcia.org\/index.php\/2019\/11\/14\/14-11-19-relacion-excluidos-cuerpo-de-maestros-por-no-participar-en-acto-interinos-del-13-11-19\/\" aria-label=\"Leer m\u00e1s sobre 14\/11\/19 Relaci\u00f3n EXCLUIDOS Cuerpo de Maestros por no participar en acto interinos del 13\/11\/19\">Leer mas<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,5],"tags":[],"class_list":["post-1553","post","type-post","status-publish","format-standard","hentry","category-actos-de-adjudicacion","category-excluidos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>14\/11\/19 Relaci\u00f3n EXCLUIDOS Cuerpo de Maestros por no participar en acto interinos del 13\/11\/19 - SIDI<\/title>\n<meta name=\"description\" content=\"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sidimurcia.org\/index.php\/2019\/11\/14\/14-11-19-relacion-excluidos-cuerpo-de-maestros-por-no-participar-en-acto-interinos-del-13-11-19\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"14\/11\/19 Relaci\u00f3n EXCLUIDOS Cuerpo de Maestros por no participar en acto interinos del 13\/11\/19 - SIDI\" \/>\n<meta property=\"og:description\" content=\"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sidimurcia.org\/index.php\/2019\/11\/14\/14-11-19-relacion-excluidos-cuerpo-de-maestros-por-no-participar-en-acto-interinos-del-13-11-19\/\" \/>\n<meta property=\"og:site_name\" content=\"SIDI\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-es.facebook.com\/sidi.sindicatodedocentes\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-14T13:39:10+00:00\" \/>\n<meta name=\"author\" content=\"Jose Luis Torrente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SIDIMURCIA\" \/>\n<meta name=\"twitter:site\" content=\"@SIDIMURCIA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jose Luis Torrente\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2019\\\/11\\\/14\\\/14-11-19-relacion-excluidos-cuerpo-de-maestros-por-no-participar-en-acto-interinos-del-13-11-19\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2019\\\/11\\\/14\\\/14-11-19-relacion-excluidos-cuerpo-de-maestros-por-no-participar-en-acto-interinos-del-13-11-19\\\/\"},\"author\":{\"name\":\"Jose Luis Torrente\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/person\\\/3f3207f88fb267669a31f8f46f76f86c\"},\"headline\":\"14\\\/11\\\/19 Relaci\u00f3n EXCLUIDOS Cuerpo de Maestros por no participar en acto interinos del 13\\\/11\\\/19\",\"datePublished\":\"2019-11-14T13:39:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2019\\\/11\\\/14\\\/14-11-19-relacion-excluidos-cuerpo-de-maestros-por-no-participar-en-acto-interinos-del-13-11-19\\\/\"},\"wordCount\":62,\"publisher\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#organization\"},\"articleSection\":[\"Actos de adjudicaci\u00f3n\",\"Excluidos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2019\\\/11\\\/14\\\/14-11-19-relacion-excluidos-cuerpo-de-maestros-por-no-participar-en-acto-interinos-del-13-11-19\\\/\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2019\\\/11\\\/14\\\/14-11-19-relacion-excluidos-cuerpo-de-maestros-por-no-participar-en-acto-interinos-del-13-11-19\\\/\",\"name\":\"14\\\/11\\\/19 Relaci\u00f3n EXCLUIDOS Cuerpo de Maestros por no participar en acto interinos del 13\\\/11\\\/19 - SIDI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#website\"},\"datePublished\":\"2019-11-14T13:39:10+00:00\",\"description\":\"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\\\/mes. Defendemos la educaci\u00f3n p\u00fablica.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2019\\\/11\\\/14\\\/14-11-19-relacion-excluidos-cuerpo-de-maestros-por-no-participar-en-acto-interinos-del-13-11-19\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2019\\\/11\\\/14\\\/14-11-19-relacion-excluidos-cuerpo-de-maestros-por-no-participar-en-acto-interinos-del-13-11-19\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2019\\\/11\\\/14\\\/14-11-19-relacion-excluidos-cuerpo-de-maestros-por-no-participar-en-acto-interinos-del-13-11-19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sidimurcia.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"14\\\/11\\\/19 Relaci\u00f3n EXCLUIDOS Cuerpo de Maestros por no participar en acto interinos del 13\\\/11\\\/19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#website\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/\",\"name\":\"SIDI\",\"description\":\"Sindicato Independiente de Docentes\",\"publisher\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sidimurcia.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#organization\",\"name\":\"Sindicato Independiente de Docentes - SIDI\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/wp-content\\\/uploads\\\/cropped-PARAPESTANAWEB-1.jpg\",\"contentUrl\":\"https:\\\/\\\/sidimurcia.org\\\/wp-content\\\/uploads\\\/cropped-PARAPESTANAWEB-1.jpg\",\"width\":512,\"height\":512,\"caption\":\"Sindicato Independiente de Docentes - SIDI\"},\"image\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-es.facebook.com\\\/sidi.sindicatodedocentes\",\"https:\\\/\\\/x.com\\\/SIDIMURCIA\",\"https:\\\/\\\/www.instagram.com\\\/sidi_murcia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCwwdL3uFtDKJdbOfmC70wIQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/person\\\/3f3207f88fb267669a31f8f46f76f86c\",\"name\":\"Jose Luis Torrente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g\",\"caption\":\"Jose Luis Torrente\"},\"url\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/author\\\/joseltorrente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"14\/11\/19 Relaci\u00f3n EXCLUIDOS Cuerpo de Maestros por no participar en acto interinos del 13\/11\/19 - SIDI","description":"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sidimurcia.org\/index.php\/2019\/11\/14\/14-11-19-relacion-excluidos-cuerpo-de-maestros-por-no-participar-en-acto-interinos-del-13-11-19\/","og_locale":"es_ES","og_type":"article","og_title":"14\/11\/19 Relaci\u00f3n EXCLUIDOS Cuerpo de Maestros por no participar en acto interinos del 13\/11\/19 - SIDI","og_description":"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.","og_url":"https:\/\/sidimurcia.org\/index.php\/2019\/11\/14\/14-11-19-relacion-excluidos-cuerpo-de-maestros-por-no-participar-en-acto-interinos-del-13-11-19\/","og_site_name":"SIDI","article_publisher":"https:\/\/es-es.facebook.com\/sidi.sindicatodedocentes","article_published_time":"2019-11-14T13:39:10+00:00","author":"Jose Luis Torrente","twitter_card":"summary_large_image","twitter_creator":"@SIDIMURCIA","twitter_site":"@SIDIMURCIA","twitter_misc":{"Escrito por":"Jose Luis Torrente"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sidimurcia.org\/index.php\/2019\/11\/14\/14-11-19-relacion-excluidos-cuerpo-de-maestros-por-no-participar-en-acto-interinos-del-13-11-19\/#article","isPartOf":{"@id":"https:\/\/sidimurcia.org\/index.php\/2019\/11\/14\/14-11-19-relacion-excluidos-cuerpo-de-maestros-por-no-participar-en-acto-interinos-del-13-11-19\/"},"author":{"name":"Jose Luis Torrente","@id":"https:\/\/sidimurcia.org\/#\/schema\/person\/3f3207f88fb267669a31f8f46f76f86c"},"headline":"14\/11\/19 Relaci\u00f3n EXCLUIDOS Cuerpo de Maestros por no participar en acto interinos del 13\/11\/19","datePublished":"2019-11-14T13:39:10+00:00","mainEntityOfPage":{"@id":"https:\/\/sidimurcia.org\/index.php\/2019\/11\/14\/14-11-19-relacion-excluidos-cuerpo-de-maestros-por-no-participar-en-acto-interinos-del-13-11-19\/"},"wordCount":62,"publisher":{"@id":"https:\/\/sidimurcia.org\/#organization"},"articleSection":["Actos de adjudicaci\u00f3n","Excluidos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/sidimurcia.org\/index.php\/2019\/11\/14\/14-11-19-relacion-excluidos-cuerpo-de-maestros-por-no-participar-en-acto-interinos-del-13-11-19\/","url":"https:\/\/sidimurcia.org\/index.php\/2019\/11\/14\/14-11-19-relacion-excluidos-cuerpo-de-maestros-por-no-participar-en-acto-interinos-del-13-11-19\/","name":"14\/11\/19 Relaci\u00f3n EXCLUIDOS Cuerpo de Maestros por no participar en acto interinos del 13\/11\/19 - SIDI","isPartOf":{"@id":"https:\/\/sidimurcia.org\/#website"},"datePublished":"2019-11-14T13:39:10+00:00","description":"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.","breadcrumb":{"@id":"https:\/\/sidimurcia.org\/index.php\/2019\/11\/14\/14-11-19-relacion-excluidos-cuerpo-de-maestros-por-no-participar-en-acto-interinos-del-13-11-19\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sidimurcia.org\/index.php\/2019\/11\/14\/14-11-19-relacion-excluidos-cuerpo-de-maestros-por-no-participar-en-acto-interinos-del-13-11-19\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sidimurcia.org\/index.php\/2019\/11\/14\/14-11-19-relacion-excluidos-cuerpo-de-maestros-por-no-participar-en-acto-interinos-del-13-11-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sidimurcia.org\/"},{"@type":"ListItem","position":2,"name":"14\/11\/19 Relaci\u00f3n EXCLUIDOS Cuerpo de Maestros por no participar en acto interinos del 13\/11\/19"}]},{"@type":"WebSite","@id":"https:\/\/sidimurcia.org\/#website","url":"https:\/\/sidimurcia.org\/","name":"SIDI","description":"Sindicato Independiente de Docentes","publisher":{"@id":"https:\/\/sidimurcia.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sidimurcia.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sidimurcia.org\/#organization","name":"Sindicato Independiente de Docentes - SIDI","url":"https:\/\/sidimurcia.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sidimurcia.org\/#\/schema\/logo\/image\/","url":"https:\/\/sidimurcia.org\/wp-content\/uploads\/cropped-PARAPESTANAWEB-1.jpg","contentUrl":"https:\/\/sidimurcia.org\/wp-content\/uploads\/cropped-PARAPESTANAWEB-1.jpg","width":512,"height":512,"caption":"Sindicato Independiente de Docentes - SIDI"},"image":{"@id":"https:\/\/sidimurcia.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-es.facebook.com\/sidi.sindicatodedocentes","https:\/\/x.com\/SIDIMURCIA","https:\/\/www.instagram.com\/sidi_murcia\/","https:\/\/www.youtube.com\/channel\/UCwwdL3uFtDKJdbOfmC70wIQ"]},{"@type":"Person","@id":"https:\/\/sidimurcia.org\/#\/schema\/person\/3f3207f88fb267669a31f8f46f76f86c","name":"Jose Luis Torrente","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g","caption":"Jose Luis Torrente"},"url":"https:\/\/sidimurcia.org\/index.php\/author\/joseltorrente\/"}]}},"_links":{"self":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/posts\/1553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/comments?post=1553"}],"version-history":[{"count":0,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/posts\/1553\/revisions"}],"wp:attachment":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/media?parent=1553"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/categories?post=1553"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/tags?post=1553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}