{"id":17875,"date":"2023-07-26T06:48:23","date_gmt":"2023-07-26T06:48:23","guid":{"rendered":"https:\/\/sidimurcia.org\/?p=17875"},"modified":"2024-11-14T07:09:13","modified_gmt":"2024-11-14T07:09:13","slug":"oposiciones-2022-aspirantes-seleccionados-que-superan-la-fase-de-practicas","status":"publish","type":"post","link":"https:\/\/sidimurcia.org\/index.php\/2023\/07\/26\/oposiciones-2022-aspirantes-seleccionados-que-superan-la-fase-de-practicas\/","title":{"rendered":"OPOSICIONES 2022: Aspirantes seleccionados que superan la fase de pr\u00e1cticas."},"content":{"rendered":"<ul>\n<li style=\"text-align: justify;\"><a class=\"enlaceMarron\" title=\"Orden de 21 de julio de 2023 de la Consejer\u00eda de Educaci\u00f3n, Formaci\u00f3n Profesional y Empleo por la que se declara que han superado la fase de pr\u00e1cticas los aspirantes seleccionados en los procedimientos selectivos convocados por Orden de 24 de febrero de 2022, y se aprueba el expediente del proceso selectivo.\" href=\"https:\/\/servicios.educarm.es\/templates\/portal\/ficheros\/websDinamicas\/45\/4595 Orden superac fase practi BORM 26-7-23.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"font-family: arial, helvetica, sans-serif;\">Orden de 21 de julio de 2023 de la Consejer\u00eda de Educaci\u00f3n, Formaci\u00f3n Profesional y Empleo por la que se declara que han superado la fase de pr\u00e1cticas los aspirantes seleccionados en los procedimientos selectivos convocados por Orden de 24 de febrero de 2022, y se aprueba el expediente del proceso selectivo.<\/span><\/a>\n<ul>\n<li><a class=\"enlaceMarron\" title=\"Orden de 5 de diciembre de 2023 por la que se modifica la Orden por la que se declara que han superado la fase de pr\u00e1cticas los aspirantes seleccionados en los procedimientos selectivos convocados por Orden de 24 de febrero de 2022, y se aprueba el expediente del proceso selectivo.\" href=\"https:\/\/servicios.educarm.es\/templates\/portal\/ficheros\/websDinamicas\/45\/Ord modif super fase practiv ops 2022 BORM 09-12-23.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"font-family: arial, helvetica, sans-serif;\">Orden de 5 de diciembre de 2023 por la que se modifica la Orden por la que se declara que han superado la fase de pr\u00e1cticas los aspirantes seleccionados en los procedimientos selectivos convocados por Orden de 24 de febrero de 2022, y se aprueba el expediente del proceso selectivo.<\/span><\/a><\/li>\n<li><a href=\"https:\/\/www.borm.es\/services\/anuncio\/ano\/2024\/numero\/3794\/pdf?id=828890\"><span style=\"font-family: arial, helvetica, sans-serif;\">Orden de 8 de julio de 2024, de la Consejer\u00eda de Educaci\u00f3n, Formaci\u00f3n Profesional y Empleo por la que se declara que han superado la fase de pr\u00e1cticas determinados aspirantes seleccionados en los procedimientos selectivos convocados por Orden de 24 de febrero de 2022.<\/span><\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/www.borm.es\/services\/anuncio\/ano\/2024\/numero\/5621\/pdf?id=831673\"><span style=\"font-family: arial, helvetica, sans-serif;\">Orden de 25 de octubre de 2024, de la Consejer\u00eda de Educaci\u00f3n y Formaci\u00f3n Profesional por la que se declara que ha superado la fase de pr\u00e1cticas determinada aspirante seleccionada en los procedimientos selectivos convocados por Orden de 24 de febrero de 2022.<\/span><\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Orden de 21 de julio de 2023 de la Consejer\u00eda de Educaci\u00f3n, Formaci\u00f3n Profesional y Empleo por la que se &#8230; <a title=\"OPOSICIONES 2022: Aspirantes seleccionados que superan la fase de pr\u00e1cticas.\" class=\"read-more\" href=\"https:\/\/sidimurcia.org\/index.php\/2023\/07\/26\/oposiciones-2022-aspirantes-seleccionados-que-superan-la-fase-de-practicas\/\" aria-label=\"Leer m\u00e1s sobre OPOSICIONES 2022: Aspirantes seleccionados que superan la fase de pr\u00e1cticas.\">Leer mas<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43,87],"tags":[],"class_list":["post-17875","post","type-post","status-publish","format-standard","hentry","category-oposiciones","category-oposiciones-2022"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>OPOSICIONES 2022: Aspirantes seleccionados que superan la fase de pr\u00e1cticas. - SIDI<\/title>\n<meta name=\"description\" content=\"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sidimurcia.org\/index.php\/2023\/07\/26\/oposiciones-2022-aspirantes-seleccionados-que-superan-la-fase-de-practicas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OPOSICIONES 2022: Aspirantes seleccionados que superan la fase de pr\u00e1cticas. - SIDI\" \/>\n<meta property=\"og:description\" content=\"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sidimurcia.org\/index.php\/2023\/07\/26\/oposiciones-2022-aspirantes-seleccionados-que-superan-la-fase-de-practicas\/\" \/>\n<meta property=\"og:site_name\" content=\"SIDI\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-es.facebook.com\/sidi.sindicatodedocentes\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-26T06:48:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-14T07:09:13+00:00\" \/>\n<meta name=\"author\" content=\"Jose Luis Torrente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SIDIMURCIA\" \/>\n<meta name=\"twitter:site\" content=\"@SIDIMURCIA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jose Luis Torrente\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2023\\\/07\\\/26\\\/oposiciones-2022-aspirantes-seleccionados-que-superan-la-fase-de-practicas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2023\\\/07\\\/26\\\/oposiciones-2022-aspirantes-seleccionados-que-superan-la-fase-de-practicas\\\/\"},\"author\":{\"name\":\"Jose Luis Torrente\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/person\\\/3f3207f88fb267669a31f8f46f76f86c\"},\"headline\":\"OPOSICIONES 2022: Aspirantes seleccionados que superan la fase de pr\u00e1cticas.\",\"datePublished\":\"2023-07-26T06:48:23+00:00\",\"dateModified\":\"2024-11-14T07:09:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2023\\\/07\\\/26\\\/oposiciones-2022-aspirantes-seleccionados-que-superan-la-fase-de-practicas\\\/\"},\"wordCount\":196,\"publisher\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#organization\"},\"articleSection\":[\"Oposiciones\",\"Oposiciones 2022\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2023\\\/07\\\/26\\\/oposiciones-2022-aspirantes-seleccionados-que-superan-la-fase-de-practicas\\\/\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2023\\\/07\\\/26\\\/oposiciones-2022-aspirantes-seleccionados-que-superan-la-fase-de-practicas\\\/\",\"name\":\"OPOSICIONES 2022: Aspirantes seleccionados que superan la fase de pr\u00e1cticas. - SIDI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#website\"},\"datePublished\":\"2023-07-26T06:48:23+00:00\",\"dateModified\":\"2024-11-14T07:09:13+00:00\",\"description\":\"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\\\/mes. Defendemos la educaci\u00f3n p\u00fablica.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2023\\\/07\\\/26\\\/oposiciones-2022-aspirantes-seleccionados-que-superan-la-fase-de-practicas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2023\\\/07\\\/26\\\/oposiciones-2022-aspirantes-seleccionados-que-superan-la-fase-de-practicas\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2023\\\/07\\\/26\\\/oposiciones-2022-aspirantes-seleccionados-que-superan-la-fase-de-practicas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sidimurcia.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OPOSICIONES 2022: Aspirantes seleccionados que superan la fase de pr\u00e1cticas.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#website\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/\",\"name\":\"SIDI\",\"description\":\"Sindicato Independiente de Docentes\",\"publisher\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sidimurcia.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#organization\",\"name\":\"Sindicato Independiente de Docentes - SIDI\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/wp-content\\\/uploads\\\/cropped-PARAPESTANAWEB-1.jpg\",\"contentUrl\":\"https:\\\/\\\/sidimurcia.org\\\/wp-content\\\/uploads\\\/cropped-PARAPESTANAWEB-1.jpg\",\"width\":512,\"height\":512,\"caption\":\"Sindicato Independiente de Docentes - SIDI\"},\"image\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-es.facebook.com\\\/sidi.sindicatodedocentes\",\"https:\\\/\\\/x.com\\\/SIDIMURCIA\",\"https:\\\/\\\/www.instagram.com\\\/sidi_murcia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCwwdL3uFtDKJdbOfmC70wIQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/person\\\/3f3207f88fb267669a31f8f46f76f86c\",\"name\":\"Jose Luis Torrente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g\",\"caption\":\"Jose Luis Torrente\"},\"url\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/author\\\/joseltorrente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OPOSICIONES 2022: Aspirantes seleccionados que superan la fase de pr\u00e1cticas. - SIDI","description":"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sidimurcia.org\/index.php\/2023\/07\/26\/oposiciones-2022-aspirantes-seleccionados-que-superan-la-fase-de-practicas\/","og_locale":"es_ES","og_type":"article","og_title":"OPOSICIONES 2022: Aspirantes seleccionados que superan la fase de pr\u00e1cticas. - SIDI","og_description":"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.","og_url":"https:\/\/sidimurcia.org\/index.php\/2023\/07\/26\/oposiciones-2022-aspirantes-seleccionados-que-superan-la-fase-de-practicas\/","og_site_name":"SIDI","article_publisher":"https:\/\/es-es.facebook.com\/sidi.sindicatodedocentes","article_published_time":"2023-07-26T06:48:23+00:00","article_modified_time":"2024-11-14T07:09:13+00:00","author":"Jose Luis Torrente","twitter_card":"summary_large_image","twitter_creator":"@SIDIMURCIA","twitter_site":"@SIDIMURCIA","twitter_misc":{"Escrito por":"Jose Luis Torrente","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sidimurcia.org\/index.php\/2023\/07\/26\/oposiciones-2022-aspirantes-seleccionados-que-superan-la-fase-de-practicas\/#article","isPartOf":{"@id":"https:\/\/sidimurcia.org\/index.php\/2023\/07\/26\/oposiciones-2022-aspirantes-seleccionados-que-superan-la-fase-de-practicas\/"},"author":{"name":"Jose Luis Torrente","@id":"https:\/\/sidimurcia.org\/#\/schema\/person\/3f3207f88fb267669a31f8f46f76f86c"},"headline":"OPOSICIONES 2022: Aspirantes seleccionados que superan la fase de pr\u00e1cticas.","datePublished":"2023-07-26T06:48:23+00:00","dateModified":"2024-11-14T07:09:13+00:00","mainEntityOfPage":{"@id":"https:\/\/sidimurcia.org\/index.php\/2023\/07\/26\/oposiciones-2022-aspirantes-seleccionados-que-superan-la-fase-de-practicas\/"},"wordCount":196,"publisher":{"@id":"https:\/\/sidimurcia.org\/#organization"},"articleSection":["Oposiciones","Oposiciones 2022"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/sidimurcia.org\/index.php\/2023\/07\/26\/oposiciones-2022-aspirantes-seleccionados-que-superan-la-fase-de-practicas\/","url":"https:\/\/sidimurcia.org\/index.php\/2023\/07\/26\/oposiciones-2022-aspirantes-seleccionados-que-superan-la-fase-de-practicas\/","name":"OPOSICIONES 2022: Aspirantes seleccionados que superan la fase de pr\u00e1cticas. - SIDI","isPartOf":{"@id":"https:\/\/sidimurcia.org\/#website"},"datePublished":"2023-07-26T06:48:23+00:00","dateModified":"2024-11-14T07:09:13+00:00","description":"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.","breadcrumb":{"@id":"https:\/\/sidimurcia.org\/index.php\/2023\/07\/26\/oposiciones-2022-aspirantes-seleccionados-que-superan-la-fase-de-practicas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sidimurcia.org\/index.php\/2023\/07\/26\/oposiciones-2022-aspirantes-seleccionados-que-superan-la-fase-de-practicas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sidimurcia.org\/index.php\/2023\/07\/26\/oposiciones-2022-aspirantes-seleccionados-que-superan-la-fase-de-practicas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sidimurcia.org\/"},{"@type":"ListItem","position":2,"name":"OPOSICIONES 2022: Aspirantes seleccionados que superan la fase de pr\u00e1cticas."}]},{"@type":"WebSite","@id":"https:\/\/sidimurcia.org\/#website","url":"https:\/\/sidimurcia.org\/","name":"SIDI","description":"Sindicato Independiente de Docentes","publisher":{"@id":"https:\/\/sidimurcia.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sidimurcia.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sidimurcia.org\/#organization","name":"Sindicato Independiente de Docentes - SIDI","url":"https:\/\/sidimurcia.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sidimurcia.org\/#\/schema\/logo\/image\/","url":"https:\/\/sidimurcia.org\/wp-content\/uploads\/cropped-PARAPESTANAWEB-1.jpg","contentUrl":"https:\/\/sidimurcia.org\/wp-content\/uploads\/cropped-PARAPESTANAWEB-1.jpg","width":512,"height":512,"caption":"Sindicato Independiente de Docentes - SIDI"},"image":{"@id":"https:\/\/sidimurcia.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-es.facebook.com\/sidi.sindicatodedocentes","https:\/\/x.com\/SIDIMURCIA","https:\/\/www.instagram.com\/sidi_murcia\/","https:\/\/www.youtube.com\/channel\/UCwwdL3uFtDKJdbOfmC70wIQ"]},{"@type":"Person","@id":"https:\/\/sidimurcia.org\/#\/schema\/person\/3f3207f88fb267669a31f8f46f76f86c","name":"Jose Luis Torrente","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g","caption":"Jose Luis Torrente"},"url":"https:\/\/sidimurcia.org\/index.php\/author\/joseltorrente\/"}]}},"_links":{"self":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/posts\/17875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/comments?post=17875"}],"version-history":[{"count":0,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/posts\/17875\/revisions"}],"wp:attachment":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/media?parent=17875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/categories?post=17875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/tags?post=17875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}