{"id":19370,"date":"2023-12-07T08:44:41","date_gmt":"2023-12-07T08:44:41","guid":{"rendered":"https:\/\/sidimurcia.org\/?p=19370"},"modified":"2024-11-11T07:30:22","modified_gmt":"2024-11-11T07:30:22","slug":"oposiciones-2022-nombramiento-como-funcionarios-de-carrera-por-orden-efp-1313-2023-boe-07-12-2023","status":"publish","type":"post","link":"https:\/\/sidimurcia.org\/index.php\/2023\/12\/07\/oposiciones-2022-nombramiento-como-funcionarios-de-carrera-por-orden-efp-1313-2023-boe-07-12-2023\/","title":{"rendered":"OPOSICIONES 2022: Nombramiento como FUNCIONARIOS DE CARRERA por Orden EFP\/1313\/2023 \u2013 BOE 07\/12\/2023"},"content":{"rendered":"<ul>\n<li style=\"text-align: justify;\"><a class=\"enlaceMarron\" title=\"Orden EFD\/1313\/2023, de 30 de noviembre, por la que, a propuesta de la Consejer\u00eda de Educaci\u00f3n, Formaci\u00f3n Profesional e Innovaci\u00f3n de la Comunidad Aut\u00f3noma de la Regi\u00f3n de Murcia, se nombra personal funcionario de carrera a las personas seleccionadas en los procedimientos selectivos convocados por Orden de 24 de febrero de 2022\" href=\"http:\/\/servicios.educarm.es\/templates\/portal\/ficheros\/websDinamicas\/45\/24915 Nombramiento pers funci maestros BOE 7-12-23 .pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"font-family: arial, helvetica, sans-serif;\">Orden EFD\/1313\/2023, de 30 de noviembre, por la que, a propuesta de la Consejer\u00eda de Educaci\u00f3n, Formaci\u00f3n Profesional e Innovaci\u00f3n de la Comunidad Aut\u00f3noma de la Regi\u00f3n de Murcia, se nombra personal funcionario de carrera a las personas seleccionadas en los procedimientos selectivos convocados por Orden de 24 de febrero de 2022<\/span><\/a>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/www.boe.es\/boe\/dias\/2024\/02\/15\/pdfs\/BOE-A-2024-2854.pdf\"><span style=\"font-family: arial, helvetica, sans-serif;\"> Orden EFD\/120\/2024, de 8 de febrero, por la que, a propuesta de la Consejer\u00eda de Educaci\u00f3n, Formaci\u00f3n Profesional y Empleo de la Comunidad Aut\u00f3noma de la Regi\u00f3n de Murcia, en estimaci\u00f3n de recurso, se nombra funcionaria de carrera, a do\u00f1a Mar\u00eda D\u00edaz Alc\u00e1zar.<\/span><\/a>\n<ul>\n<li><a class=\"enlaceMarron\" title=\"Orden EFD\/179\/2024, de 25 de febrero, por la que se corrigen errores en la Orden EFD\/120\/2024, de 8 de febrero, por la que, a propuesta de la Consejer\u00eda de Educaci\u00f3n, Formaci\u00f3n Profesional y Empleo de la Comunidad Aut\u00f3noma de la Regi\u00f3n de Murcia, en estimaci\u00f3n de recurso, se nombra funcionaria de carrera a do\u00f1a Mar\u00eda D\u00edaz Alc\u00e1zar\" href=\"https:\/\/servicios.educarm.es\/templates\/portal\/ficheros\/websDinamicas\/45\/Correc error Ord nombr func carr eemm BOE 01-03-24.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"font-family: arial, helvetica, sans-serif;\">Orden EFD\/179\/2024, de 25 de febrero, por la que se corrigen errores en la Orden EFD\/120\/2024, de 8 de febrero, por la que, a propuesta de la Consejer\u00eda de Educaci\u00f3n, Formaci\u00f3n Profesional y Empleo de la Comunidad Aut\u00f3noma de la Regi\u00f3n de Murcia, en estimaci\u00f3n de recurso, se nombra funcionaria de carrera a do\u00f1a Mar\u00eda D\u00edaz Alc\u00e1zar<\/span><\/a><\/li>\n<\/ul>\n<\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/servicios.educarm.es\/templates\/portal\/ficheros\/websDinamicas\/45\/Correc%20error%20Ord%20nombr%20func%20carrer%20cuerp%20maestros%20opos%202022%20BOE%2021-02-24.pdf\"><span style=\"font-family: arial, helvetica, sans-serif;\">Orden EFD\/137\/2024, de 15 de febrero, por la que se corrigen errores en la Orden EFD\/1313\/2023, de 30 de noviembre, por la que, a propuesta de la Consejer\u00eda de Educaci\u00f3n, Formaci\u00f3n Profesional e Innovaci\u00f3n de la Comunidad Aut\u00f3noma de la Regi\u00f3n de Murcia, se nombra personal funcionario de carrera a las personas seleccionadas en los procedimientos selectivos convocados por Orden de 24 de febrero de 2022. Plazo interponer recurso: De 22 de febrero de 2024 a 21 de marzo de 2024.<\/span><\/a><\/li>\n<li style=\"text-align: justify;\"><a class=\"enlaceMarron\" title=\"Orden EFD\/1241\/2024, de 31 de octubre, por la que, a propuesta de la Consejer\u00eda de Educaci\u00f3n y Formaci\u00f3n Profesional de la Comunidad Aut\u00f3noma de la Regi\u00f3n de Murcia, se nombra personal funcionario de carrera en el Cuerpo de Maestros, a aspirantes que superaron el proceso selectivo convocado por Orden de 24 de febrero de 2022\" href=\"https:\/\/servicios.educarm.es\/templates\/portal\/ficheros\/websDinamicas\/45\/Ord nombr func carrer Maestr conv 2022 BOE 11-11-24.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"font-family: arial, helvetica, sans-serif;\">Orden EFD\/1241\/2024, de 31 de octubre, por la que, a propuesta de la Consejer\u00eda de Educaci\u00f3n y Formaci\u00f3n Profesional de la Comunidad Aut\u00f3noma de la Regi\u00f3n de Murcia, se nombra personal funcionario de carrera en el Cuerpo de Maestros, a aspirantes que superaron el proceso selectivo convocado por Orden de 24 de febrero de 2022<\/span><\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Orden EFD\/1313\/2023, de 30 de noviembre, por la que, a propuesta de la Consejer\u00eda de Educaci\u00f3n, Formaci\u00f3n Profesional e Innovaci\u00f3n &#8230; <a title=\"OPOSICIONES 2022: Nombramiento como FUNCIONARIOS DE CARRERA por Orden EFP\/1313\/2023 \u2013 BOE 07\/12\/2023\" class=\"read-more\" href=\"https:\/\/sidimurcia.org\/index.php\/2023\/12\/07\/oposiciones-2022-nombramiento-como-funcionarios-de-carrera-por-orden-efp-1313-2023-boe-07-12-2023\/\" aria-label=\"Leer m\u00e1s sobre OPOSICIONES 2022: Nombramiento como FUNCIONARIOS DE CARRERA por Orden EFP\/1313\/2023 \u2013 BOE 07\/12\/2023\">Leer mas<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43,87],"tags":[],"class_list":["post-19370","post","type-post","status-publish","format-standard","hentry","category-oposiciones","category-oposiciones-2022"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>OPOSICIONES 2022: Nombramiento como FUNCIONARIOS DE CARRERA por Orden EFP\/1313\/2023 \u2013 BOE 07\/12\/2023 - SIDI<\/title>\n<meta name=\"description\" content=\"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sidimurcia.org\/index.php\/2023\/12\/07\/oposiciones-2022-nombramiento-como-funcionarios-de-carrera-por-orden-efp-1313-2023-boe-07-12-2023\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OPOSICIONES 2022: Nombramiento como FUNCIONARIOS DE CARRERA por Orden EFP\/1313\/2023 \u2013 BOE 07\/12\/2023 - SIDI\" \/>\n<meta property=\"og:description\" content=\"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sidimurcia.org\/index.php\/2023\/12\/07\/oposiciones-2022-nombramiento-como-funcionarios-de-carrera-por-orden-efp-1313-2023-boe-07-12-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"SIDI\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-es.facebook.com\/sidi.sindicatodedocentes\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-07T08:44:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-11T07:30:22+00:00\" \/>\n<meta name=\"author\" content=\"Jose Luis Torrente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SIDIMURCIA\" \/>\n<meta name=\"twitter:site\" content=\"@SIDIMURCIA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jose Luis Torrente\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2023\\\/12\\\/07\\\/oposiciones-2022-nombramiento-como-funcionarios-de-carrera-por-orden-efp-1313-2023-boe-07-12-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2023\\\/12\\\/07\\\/oposiciones-2022-nombramiento-como-funcionarios-de-carrera-por-orden-efp-1313-2023-boe-07-12-2023\\\/\"},\"author\":{\"name\":\"Jose Luis Torrente\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/person\\\/3f3207f88fb267669a31f8f46f76f86c\"},\"headline\":\"OPOSICIONES 2022: Nombramiento como FUNCIONARIOS DE CARRERA por Orden EFP\\\/1313\\\/2023 \u2013 BOE 07\\\/12\\\/2023\",\"datePublished\":\"2023-12-07T08:44:41+00:00\",\"dateModified\":\"2024-11-11T07:30:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2023\\\/12\\\/07\\\/oposiciones-2022-nombramiento-como-funcionarios-de-carrera-por-orden-efp-1313-2023-boe-07-12-2023\\\/\"},\"wordCount\":318,\"publisher\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#organization\"},\"articleSection\":[\"Oposiciones\",\"Oposiciones 2022\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2023\\\/12\\\/07\\\/oposiciones-2022-nombramiento-como-funcionarios-de-carrera-por-orden-efp-1313-2023-boe-07-12-2023\\\/\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2023\\\/12\\\/07\\\/oposiciones-2022-nombramiento-como-funcionarios-de-carrera-por-orden-efp-1313-2023-boe-07-12-2023\\\/\",\"name\":\"OPOSICIONES 2022: Nombramiento como FUNCIONARIOS DE CARRERA por Orden EFP\\\/1313\\\/2023 \u2013 BOE 07\\\/12\\\/2023 - SIDI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#website\"},\"datePublished\":\"2023-12-07T08:44:41+00:00\",\"dateModified\":\"2024-11-11T07:30:22+00:00\",\"description\":\"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\\\/mes. Defendemos la educaci\u00f3n p\u00fablica.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2023\\\/12\\\/07\\\/oposiciones-2022-nombramiento-como-funcionarios-de-carrera-por-orden-efp-1313-2023-boe-07-12-2023\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2023\\\/12\\\/07\\\/oposiciones-2022-nombramiento-como-funcionarios-de-carrera-por-orden-efp-1313-2023-boe-07-12-2023\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2023\\\/12\\\/07\\\/oposiciones-2022-nombramiento-como-funcionarios-de-carrera-por-orden-efp-1313-2023-boe-07-12-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sidimurcia.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OPOSICIONES 2022: Nombramiento como FUNCIONARIOS DE CARRERA por Orden EFP\\\/1313\\\/2023 \u2013 BOE 07\\\/12\\\/2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#website\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/\",\"name\":\"SIDI\",\"description\":\"Sindicato Independiente de Docentes\",\"publisher\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sidimurcia.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#organization\",\"name\":\"Sindicato Independiente de Docentes - SIDI\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/wp-content\\\/uploads\\\/cropped-PARAPESTANAWEB-1.jpg\",\"contentUrl\":\"https:\\\/\\\/sidimurcia.org\\\/wp-content\\\/uploads\\\/cropped-PARAPESTANAWEB-1.jpg\",\"width\":512,\"height\":512,\"caption\":\"Sindicato Independiente de Docentes - SIDI\"},\"image\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-es.facebook.com\\\/sidi.sindicatodedocentes\",\"https:\\\/\\\/x.com\\\/SIDIMURCIA\",\"https:\\\/\\\/www.instagram.com\\\/sidi_murcia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCwwdL3uFtDKJdbOfmC70wIQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/person\\\/3f3207f88fb267669a31f8f46f76f86c\",\"name\":\"Jose Luis Torrente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g\",\"caption\":\"Jose Luis Torrente\"},\"url\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/author\\\/joseltorrente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OPOSICIONES 2022: Nombramiento como FUNCIONARIOS DE CARRERA por Orden EFP\/1313\/2023 \u2013 BOE 07\/12\/2023 - SIDI","description":"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sidimurcia.org\/index.php\/2023\/12\/07\/oposiciones-2022-nombramiento-como-funcionarios-de-carrera-por-orden-efp-1313-2023-boe-07-12-2023\/","og_locale":"es_ES","og_type":"article","og_title":"OPOSICIONES 2022: Nombramiento como FUNCIONARIOS DE CARRERA por Orden EFP\/1313\/2023 \u2013 BOE 07\/12\/2023 - SIDI","og_description":"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.","og_url":"https:\/\/sidimurcia.org\/index.php\/2023\/12\/07\/oposiciones-2022-nombramiento-como-funcionarios-de-carrera-por-orden-efp-1313-2023-boe-07-12-2023\/","og_site_name":"SIDI","article_publisher":"https:\/\/es-es.facebook.com\/sidi.sindicatodedocentes","article_published_time":"2023-12-07T08:44:41+00:00","article_modified_time":"2024-11-11T07:30:22+00:00","author":"Jose Luis Torrente","twitter_card":"summary_large_image","twitter_creator":"@SIDIMURCIA","twitter_site":"@SIDIMURCIA","twitter_misc":{"Escrito por":"Jose Luis Torrente","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sidimurcia.org\/index.php\/2023\/12\/07\/oposiciones-2022-nombramiento-como-funcionarios-de-carrera-por-orden-efp-1313-2023-boe-07-12-2023\/#article","isPartOf":{"@id":"https:\/\/sidimurcia.org\/index.php\/2023\/12\/07\/oposiciones-2022-nombramiento-como-funcionarios-de-carrera-por-orden-efp-1313-2023-boe-07-12-2023\/"},"author":{"name":"Jose Luis Torrente","@id":"https:\/\/sidimurcia.org\/#\/schema\/person\/3f3207f88fb267669a31f8f46f76f86c"},"headline":"OPOSICIONES 2022: Nombramiento como FUNCIONARIOS DE CARRERA por Orden EFP\/1313\/2023 \u2013 BOE 07\/12\/2023","datePublished":"2023-12-07T08:44:41+00:00","dateModified":"2024-11-11T07:30:22+00:00","mainEntityOfPage":{"@id":"https:\/\/sidimurcia.org\/index.php\/2023\/12\/07\/oposiciones-2022-nombramiento-como-funcionarios-de-carrera-por-orden-efp-1313-2023-boe-07-12-2023\/"},"wordCount":318,"publisher":{"@id":"https:\/\/sidimurcia.org\/#organization"},"articleSection":["Oposiciones","Oposiciones 2022"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/sidimurcia.org\/index.php\/2023\/12\/07\/oposiciones-2022-nombramiento-como-funcionarios-de-carrera-por-orden-efp-1313-2023-boe-07-12-2023\/","url":"https:\/\/sidimurcia.org\/index.php\/2023\/12\/07\/oposiciones-2022-nombramiento-como-funcionarios-de-carrera-por-orden-efp-1313-2023-boe-07-12-2023\/","name":"OPOSICIONES 2022: Nombramiento como FUNCIONARIOS DE CARRERA por Orden EFP\/1313\/2023 \u2013 BOE 07\/12\/2023 - SIDI","isPartOf":{"@id":"https:\/\/sidimurcia.org\/#website"},"datePublished":"2023-12-07T08:44:41+00:00","dateModified":"2024-11-11T07:30:22+00:00","description":"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.","breadcrumb":{"@id":"https:\/\/sidimurcia.org\/index.php\/2023\/12\/07\/oposiciones-2022-nombramiento-como-funcionarios-de-carrera-por-orden-efp-1313-2023-boe-07-12-2023\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sidimurcia.org\/index.php\/2023\/12\/07\/oposiciones-2022-nombramiento-como-funcionarios-de-carrera-por-orden-efp-1313-2023-boe-07-12-2023\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sidimurcia.org\/index.php\/2023\/12\/07\/oposiciones-2022-nombramiento-como-funcionarios-de-carrera-por-orden-efp-1313-2023-boe-07-12-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sidimurcia.org\/"},{"@type":"ListItem","position":2,"name":"OPOSICIONES 2022: Nombramiento como FUNCIONARIOS DE CARRERA por Orden EFP\/1313\/2023 \u2013 BOE 07\/12\/2023"}]},{"@type":"WebSite","@id":"https:\/\/sidimurcia.org\/#website","url":"https:\/\/sidimurcia.org\/","name":"SIDI","description":"Sindicato Independiente de Docentes","publisher":{"@id":"https:\/\/sidimurcia.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sidimurcia.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sidimurcia.org\/#organization","name":"Sindicato Independiente de Docentes - SIDI","url":"https:\/\/sidimurcia.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sidimurcia.org\/#\/schema\/logo\/image\/","url":"https:\/\/sidimurcia.org\/wp-content\/uploads\/cropped-PARAPESTANAWEB-1.jpg","contentUrl":"https:\/\/sidimurcia.org\/wp-content\/uploads\/cropped-PARAPESTANAWEB-1.jpg","width":512,"height":512,"caption":"Sindicato Independiente de Docentes - SIDI"},"image":{"@id":"https:\/\/sidimurcia.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-es.facebook.com\/sidi.sindicatodedocentes","https:\/\/x.com\/SIDIMURCIA","https:\/\/www.instagram.com\/sidi_murcia\/","https:\/\/www.youtube.com\/channel\/UCwwdL3uFtDKJdbOfmC70wIQ"]},{"@type":"Person","@id":"https:\/\/sidimurcia.org\/#\/schema\/person\/3f3207f88fb267669a31f8f46f76f86c","name":"Jose Luis Torrente","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g","caption":"Jose Luis Torrente"},"url":"https:\/\/sidimurcia.org\/index.php\/author\/joseltorrente\/"}]}},"_links":{"self":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/posts\/19370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/comments?post=19370"}],"version-history":[{"count":0,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/posts\/19370\/revisions"}],"wp:attachment":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/media?parent=19370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/categories?post=19370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/tags?post=19370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}