{"id":2905,"date":"2020-02-19T13:24:09","date_gmt":"2020-02-19T13:24:09","guid":{"rendered":"https:\/\/sidimurcia.org\/?p=2905"},"modified":"2020-10-19T12:27:39","modified_gmt":"2020-10-19T12:27:39","slug":"portugal-profesores-interinos-en-programas-educativos-en-el-exterior-ies-espanol-giner-de-los-rios-curso-20-21","status":"publish","type":"post","link":"https:\/\/sidimurcia.org\/index.php\/2020\/02\/19\/portugal-profesores-interinos-en-programas-educativos-en-el-exterior-ies-espanol-giner-de-los-rios-curso-20-21\/","title":{"rendered":"PORTUGAL: Profesores interinos en programas educativos en el exterior, IES Espa\u00f1ol Giner de los Rios, curso 20\/21"},"content":{"rendered":"<ul>\n<li style=\"text-align: justify;\"><a href=\"http:\/\/servicios.educarm.es\/templates\/portal\/ficheros\/websDinamicas\/45\/Convocatoria%202020-2021%20web%20mec%2019-02-20.pdf\">Convocatoria de la Consejer\u00eda de Educaci\u00f3n en Portugal para la formaci\u00f3n de las listas de aspirantes a desempe\u00f1ar puestos en r\u00e9gimen de interinidad de los cuerpos de Maestros y de Profesores de Ense\u00f1anza Secundaria contemplados en la Ley org\u00e1nica 2\/2006, de 3 de mayo, de Educaci\u00f3n, en plazas docentes en el Instituto Espa\u00f1ol \u00abGiner de los R\u00edos\u00bb de Lisboa, para el curso 2020-2021.<\/a><\/li>\n<\/ul>\n<p style=\"text-align: center;\"><a class=\"boton\" title=\"Enlace externo, se abre en ventana nueva.\" href=\"https:\/\/sede.educacion.gob.es\/sede\/login\/inicio.jjsp?idConvocatoria=1367\" target=\"_blank\" rel=\"external noopener noreferrer\"><strong>Acceso a la solicitud online<\/strong><\/a><\/p>\n<p><span style=\"color: #800080;\"><strong>Plazo presentaci\u00f3n solicitudes: Desde el 18 de febrero de 2020 a las 00:00 hasta el 03 de marzo de 2020 a las 23:00<\/strong><\/span><\/p>\n<p><strong>ESPECIALIDADES CONVOCADAS:<\/strong><\/p>\n<p><span style=\"text-decoration: underline;\">MAESTROS<\/span><br \/>\n* Educaci\u00f3n Primaria<br \/>\n* Educaci\u00f3n Infantil<br \/>\n* Idioma extranjero: Ingl\u00e9s<br \/>\n* M\u00fasica<br \/>\n* Educaci\u00f3n F\u00edsica<\/p>\n<p><span style=\"text-decoration: underline;\">PROFESORES DE EDUCACI\u00d3N SECUNDARIA<\/span><br \/>\n* F\u00edsica y Qu\u00edmica<br \/>\n* Matem\u00e1ticas<\/p>\n<p>* Ingl\u00e9s<br \/>\n* Franc\u00e9s<br \/>\n* Tecnolog\u00eda<br \/>\n* Filosof\u00eda<br \/>\n* Lengua Castellana y Literatura<br \/>\n* Geograf\u00eda e Historia<br \/>\n* Biolog\u00eda y Geolog\u00eda<br \/>\n* Dibujo<br \/>\n* M\u00fasica<br \/>\n* Educaci\u00f3n F\u00edsica<br \/>\n* Orientaci\u00f3n Educativa<\/p>\n<div class=\"subseccion\">\n<h3 id=\"ds3\">Instrucciones:<\/h3>\n<div class=\"cte\">\n<p><a title=\"Enlace externo, se abre en ventana nueva.\" href=\"http:\/\/www.educacionyfp.gob.es\/dam\/jcr:9349ae5b-5739-481c-b3dc-54bb48d41a96\/manualcandidato.pdf\" target=\"_blank\" rel=\"external noopener noreferrer\">Manual del candidato<\/a><\/p>\n<p><a title=\"Enlace externo, se abre en ventana nueva.\" href=\"http:\/\/www.educacionyfp.gob.es\/dam\/jcr:da2db1cd-0e82-4ca4-9d52-29a0ac931afe\/manualsubsanacion.pdf\" target=\"_blank\" rel=\"external noopener noreferrer\">Manual para subsanaci\u00f3n<\/a><\/p>\n<p><strong>Anexos:<\/strong><\/p>\n<p class=\"ml-40px\"><a title=\"Enlace externo, se abre en ventana nueva.\" href=\"http:\/\/www.educacionyfp.gob.es\/dam\/jcr:58a11f60-99fd-4ce1-a52c-91a5f1cf822e\/anexoi.pdf\" target=\"_blank\" rel=\"external noopener noreferrer\">Anexo I <\/a>Baremo de valoraci\u00f3n de m\u00e9ritos.<\/p>\n<p class=\"ml-40px\"><a title=\"Enlace externo, se abre en ventana nueva.\" href=\"http:\/\/www.educacionyfp.gob.es\/dam\/jcr:97f757e6-dedd-4124-ac04-310e6604b380\/anexoii.pdf\" target=\"_blank\" rel=\"external noopener noreferrer\">Anexo II<\/a> Titulaciones acad\u00e9micas por Cuerpos y Especialidades.<\/p>\n<p class=\"ml-40px\"><a title=\"Enlace externo, se abre en ventana nueva.\" href=\"http:\/\/www.educacionyfp.gob.es\/dam\/jcr:43400b40-b8ea-4cad-a79b-dafe4d412082\/anexoiii.pdf\" target=\"_blank\" rel=\"external noopener noreferrer\">Anexo III<\/a> Especialidades convocadas.<\/p>\n<p><a href=\"http:\/\/www.educacionyfp.gob.es\/servicios-al-ciudadano\/catalogo\/general\/20\/200334\/portugal\/200334-interinos-portugal-2020-2021.html\">DISPONES DE TODA LA INFORMACI\u00d3N EN ESTE ENLACE<\/a><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Convocatoria de la Consejer\u00eda de Educaci\u00f3n en Portugal para la formaci\u00f3n de las listas de aspirantes a desempe\u00f1ar puestos en &#8230; <a title=\"PORTUGAL: Profesores interinos en programas educativos en el exterior, IES Espa\u00f1ol Giner de los Rios, curso 20\/21\" class=\"read-more\" href=\"https:\/\/sidimurcia.org\/index.php\/2020\/02\/19\/portugal-profesores-interinos-en-programas-educativos-en-el-exterior-ies-espanol-giner-de-los-rios-curso-20-21\/\" aria-label=\"Leer m\u00e1s sobre PORTUGAL: Profesores interinos en programas educativos en el exterior, IES Espa\u00f1ol Giner de los Rios, curso 20\/21\">Leer mas<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,83],"tags":[],"class_list":["post-2905","post","type-post","status-publish","format-standard","hentry","category-bolsa-extraordinaria","category-convocatoria-otros-paises"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PORTUGAL: Profesores interinos en programas educativos en el exterior, IES Espa\u00f1ol Giner de los Rios, curso 20\/21 - SIDI<\/title>\n<meta name=\"description\" content=\"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sidimurcia.org\/index.php\/2020\/02\/19\/portugal-profesores-interinos-en-programas-educativos-en-el-exterior-ies-espanol-giner-de-los-rios-curso-20-21\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PORTUGAL: Profesores interinos en programas educativos en el exterior, IES Espa\u00f1ol Giner de los Rios, curso 20\/21 - SIDI\" \/>\n<meta property=\"og:description\" content=\"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sidimurcia.org\/index.php\/2020\/02\/19\/portugal-profesores-interinos-en-programas-educativos-en-el-exterior-ies-espanol-giner-de-los-rios-curso-20-21\/\" \/>\n<meta property=\"og:site_name\" content=\"SIDI\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-es.facebook.com\/sidi.sindicatodedocentes\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-19T13:24:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-19T12:27:39+00:00\" \/>\n<meta name=\"author\" content=\"Jose Luis Torrente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SIDIMURCIA\" \/>\n<meta name=\"twitter:site\" content=\"@SIDIMURCIA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jose Luis Torrente\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2020\\\/02\\\/19\\\/portugal-profesores-interinos-en-programas-educativos-en-el-exterior-ies-espanol-giner-de-los-rios-curso-20-21\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2020\\\/02\\\/19\\\/portugal-profesores-interinos-en-programas-educativos-en-el-exterior-ies-espanol-giner-de-los-rios-curso-20-21\\\/\"},\"author\":{\"name\":\"Jose Luis Torrente\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/person\\\/3f3207f88fb267669a31f8f46f76f86c\"},\"headline\":\"PORTUGAL: Profesores interinos en programas educativos en el exterior, IES Espa\u00f1ol Giner de los Rios, curso 20\\\/21\",\"datePublished\":\"2020-02-19T13:24:09+00:00\",\"dateModified\":\"2020-10-19T12:27:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2020\\\/02\\\/19\\\/portugal-profesores-interinos-en-programas-educativos-en-el-exterior-ies-espanol-giner-de-los-rios-curso-20-21\\\/\"},\"wordCount\":213,\"publisher\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#organization\"},\"articleSection\":[\"Bolsa Extraordinaria\",\"Convocatoria otros paises\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2020\\\/02\\\/19\\\/portugal-profesores-interinos-en-programas-educativos-en-el-exterior-ies-espanol-giner-de-los-rios-curso-20-21\\\/\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2020\\\/02\\\/19\\\/portugal-profesores-interinos-en-programas-educativos-en-el-exterior-ies-espanol-giner-de-los-rios-curso-20-21\\\/\",\"name\":\"PORTUGAL: Profesores interinos en programas educativos en el exterior, IES Espa\u00f1ol Giner de los Rios, curso 20\\\/21 - SIDI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#website\"},\"datePublished\":\"2020-02-19T13:24:09+00:00\",\"dateModified\":\"2020-10-19T12:27:39+00:00\",\"description\":\"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\\\/mes. Defendemos la educaci\u00f3n p\u00fablica.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2020\\\/02\\\/19\\\/portugal-profesores-interinos-en-programas-educativos-en-el-exterior-ies-espanol-giner-de-los-rios-curso-20-21\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2020\\\/02\\\/19\\\/portugal-profesores-interinos-en-programas-educativos-en-el-exterior-ies-espanol-giner-de-los-rios-curso-20-21\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2020\\\/02\\\/19\\\/portugal-profesores-interinos-en-programas-educativos-en-el-exterior-ies-espanol-giner-de-los-rios-curso-20-21\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sidimurcia.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PORTUGAL: Profesores interinos en programas educativos en el exterior, IES Espa\u00f1ol Giner de los Rios, curso 20\\\/21\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#website\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/\",\"name\":\"SIDI\",\"description\":\"Sindicato Independiente de Docentes\",\"publisher\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sidimurcia.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#organization\",\"name\":\"Sindicato Independiente de Docentes - SIDI\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/wp-content\\\/uploads\\\/cropped-PARAPESTANAWEB-1.jpg\",\"contentUrl\":\"https:\\\/\\\/sidimurcia.org\\\/wp-content\\\/uploads\\\/cropped-PARAPESTANAWEB-1.jpg\",\"width\":512,\"height\":512,\"caption\":\"Sindicato Independiente de Docentes - SIDI\"},\"image\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-es.facebook.com\\\/sidi.sindicatodedocentes\",\"https:\\\/\\\/x.com\\\/SIDIMURCIA\",\"https:\\\/\\\/www.instagram.com\\\/sidi_murcia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCwwdL3uFtDKJdbOfmC70wIQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/person\\\/3f3207f88fb267669a31f8f46f76f86c\",\"name\":\"Jose Luis Torrente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g\",\"caption\":\"Jose Luis Torrente\"},\"url\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/author\\\/joseltorrente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PORTUGAL: Profesores interinos en programas educativos en el exterior, IES Espa\u00f1ol Giner de los Rios, curso 20\/21 - SIDI","description":"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sidimurcia.org\/index.php\/2020\/02\/19\/portugal-profesores-interinos-en-programas-educativos-en-el-exterior-ies-espanol-giner-de-los-rios-curso-20-21\/","og_locale":"es_ES","og_type":"article","og_title":"PORTUGAL: Profesores interinos en programas educativos en el exterior, IES Espa\u00f1ol Giner de los Rios, curso 20\/21 - SIDI","og_description":"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.","og_url":"https:\/\/sidimurcia.org\/index.php\/2020\/02\/19\/portugal-profesores-interinos-en-programas-educativos-en-el-exterior-ies-espanol-giner-de-los-rios-curso-20-21\/","og_site_name":"SIDI","article_publisher":"https:\/\/es-es.facebook.com\/sidi.sindicatodedocentes","article_published_time":"2020-02-19T13:24:09+00:00","article_modified_time":"2020-10-19T12:27:39+00:00","author":"Jose Luis Torrente","twitter_card":"summary_large_image","twitter_creator":"@SIDIMURCIA","twitter_site":"@SIDIMURCIA","twitter_misc":{"Escrito por":"Jose Luis Torrente","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sidimurcia.org\/index.php\/2020\/02\/19\/portugal-profesores-interinos-en-programas-educativos-en-el-exterior-ies-espanol-giner-de-los-rios-curso-20-21\/#article","isPartOf":{"@id":"https:\/\/sidimurcia.org\/index.php\/2020\/02\/19\/portugal-profesores-interinos-en-programas-educativos-en-el-exterior-ies-espanol-giner-de-los-rios-curso-20-21\/"},"author":{"name":"Jose Luis Torrente","@id":"https:\/\/sidimurcia.org\/#\/schema\/person\/3f3207f88fb267669a31f8f46f76f86c"},"headline":"PORTUGAL: Profesores interinos en programas educativos en el exterior, IES Espa\u00f1ol Giner de los Rios, curso 20\/21","datePublished":"2020-02-19T13:24:09+00:00","dateModified":"2020-10-19T12:27:39+00:00","mainEntityOfPage":{"@id":"https:\/\/sidimurcia.org\/index.php\/2020\/02\/19\/portugal-profesores-interinos-en-programas-educativos-en-el-exterior-ies-espanol-giner-de-los-rios-curso-20-21\/"},"wordCount":213,"publisher":{"@id":"https:\/\/sidimurcia.org\/#organization"},"articleSection":["Bolsa Extraordinaria","Convocatoria otros paises"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/sidimurcia.org\/index.php\/2020\/02\/19\/portugal-profesores-interinos-en-programas-educativos-en-el-exterior-ies-espanol-giner-de-los-rios-curso-20-21\/","url":"https:\/\/sidimurcia.org\/index.php\/2020\/02\/19\/portugal-profesores-interinos-en-programas-educativos-en-el-exterior-ies-espanol-giner-de-los-rios-curso-20-21\/","name":"PORTUGAL: Profesores interinos en programas educativos en el exterior, IES Espa\u00f1ol Giner de los Rios, curso 20\/21 - SIDI","isPartOf":{"@id":"https:\/\/sidimurcia.org\/#website"},"datePublished":"2020-02-19T13:24:09+00:00","dateModified":"2020-10-19T12:27:39+00:00","description":"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.","breadcrumb":{"@id":"https:\/\/sidimurcia.org\/index.php\/2020\/02\/19\/portugal-profesores-interinos-en-programas-educativos-en-el-exterior-ies-espanol-giner-de-los-rios-curso-20-21\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sidimurcia.org\/index.php\/2020\/02\/19\/portugal-profesores-interinos-en-programas-educativos-en-el-exterior-ies-espanol-giner-de-los-rios-curso-20-21\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sidimurcia.org\/index.php\/2020\/02\/19\/portugal-profesores-interinos-en-programas-educativos-en-el-exterior-ies-espanol-giner-de-los-rios-curso-20-21\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sidimurcia.org\/"},{"@type":"ListItem","position":2,"name":"PORTUGAL: Profesores interinos en programas educativos en el exterior, IES Espa\u00f1ol Giner de los Rios, curso 20\/21"}]},{"@type":"WebSite","@id":"https:\/\/sidimurcia.org\/#website","url":"https:\/\/sidimurcia.org\/","name":"SIDI","description":"Sindicato Independiente de Docentes","publisher":{"@id":"https:\/\/sidimurcia.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sidimurcia.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sidimurcia.org\/#organization","name":"Sindicato Independiente de Docentes - SIDI","url":"https:\/\/sidimurcia.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sidimurcia.org\/#\/schema\/logo\/image\/","url":"https:\/\/sidimurcia.org\/wp-content\/uploads\/cropped-PARAPESTANAWEB-1.jpg","contentUrl":"https:\/\/sidimurcia.org\/wp-content\/uploads\/cropped-PARAPESTANAWEB-1.jpg","width":512,"height":512,"caption":"Sindicato Independiente de Docentes - SIDI"},"image":{"@id":"https:\/\/sidimurcia.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-es.facebook.com\/sidi.sindicatodedocentes","https:\/\/x.com\/SIDIMURCIA","https:\/\/www.instagram.com\/sidi_murcia\/","https:\/\/www.youtube.com\/channel\/UCwwdL3uFtDKJdbOfmC70wIQ"]},{"@type":"Person","@id":"https:\/\/sidimurcia.org\/#\/schema\/person\/3f3207f88fb267669a31f8f46f76f86c","name":"Jose Luis Torrente","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g","caption":"Jose Luis Torrente"},"url":"https:\/\/sidimurcia.org\/index.php\/author\/joseltorrente\/"}]}},"_links":{"self":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/posts\/2905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/comments?post=2905"}],"version-history":[{"count":0,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/posts\/2905\/revisions"}],"wp:attachment":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/media?parent=2905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/categories?post=2905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/tags?post=2905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}