{"id":4469,"date":"2020-06-13T07:36:49","date_gmt":"2020-06-13T07:36:49","guid":{"rendered":"https:\/\/sidimurcia.org\/?p=4469"},"modified":"2020-10-19T11:35:21","modified_gmt":"2020-10-19T11:35:21","slug":"convocatoria-de-procedimiento-extraordinario-para-la-seleccion-de-personal-interino-varias-especialidades-de-secundaria","status":"publish","type":"post","link":"https:\/\/sidimurcia.org\/index.php\/2020\/06\/13\/convocatoria-de-procedimiento-extraordinario-para-la-seleccion-de-personal-interino-varias-especialidades-de-secundaria\/","title":{"rendered":"BOLSA EXTRAORDINARIA &#8211; Convocatoria de procedimiento extraordinario para la selecci\u00f3n de personal interino para varias especialidades de Secundaria"},"content":{"rendered":"<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/www.carm.es\/web\/integra.servlets.Blob?ARCHIVO=Orden.pdf&amp;TABLA=ARCHIVOS&amp;CAMPOCLAVE=IDARCHIVO&amp;VALORCLAVE=163714&amp;CAMPOIMAGEN=ARCHIVO&amp;IDTIPO=60&amp;RASTRO=c77$m22725,22759,4254\">Orden de 29 de mayo de 2020 de la Consejer\u00eda de Educaci\u00f3n y Cultura por la que se convoca procedimiento extraordinario para la selecci\u00f3n de personal interino para cubrir plazas vacantes o sustituciones en determinadas especialidades del Cuerpo de Profesores de Ense\u00f1anza Secundaria<\/a><\/li>\n<\/ul>\n<p><span style=\"color: #800080;\"><strong>Plazo de presentaci\u00f3n de solicitudes: Desde el 15 de junio a las 00:00 horas hasta el 29 de junio a las 13:00 horas.<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">La solicitud de participaci\u00f3n estar\u00e1 disponible en la sede electr\u00f3nica de la Comunidad Aut\u00f3noma de la Regi\u00f3n de Murcia <a href=\"https:\/\/sede.carm.es\/web\/pagina?IDCONTENIDO=1897&amp;IDTIPO=240&amp;RASTRO=c$m40288\">(http:\/\/sede.carm.es) con el n\u00famero de procedimiento 1897.<\/a><\/p>\n<p><strong> Firma electr\u00f3nica de las solicitudes:<\/strong><\/p>\n<ul>\n<li>sistema \u201ccl@ve\u201d<\/li>\n<li>certificado digital (F\u00e1brica Nacional de Moneda y Timbre y Documento Nacional de Identidad Electr\u00f3nico)<\/li>\n<li>usuario y contrase\u00f1a de educarm ( debes estar en actuales listas de interinos y haber prestado servicios en centros p\u00fablicos)<\/li>\n<\/ul>\n<p><strong>Especialidades ofertadas:<\/strong><\/p>\n<p>006 Matem\u00e1ticas<br \/>\n009 Dibujo<br \/>\n010 Franc\u00e9s<br \/>\n016 M\u00fasica<br \/>\n017 Educaci\u00f3n F\u00edsica<br \/>\n019 Tecnolog\u00eda<\/p>\n<p style=\"text-align: justify;\"><strong>Requisitos espec\u00edficos de titulaci\u00f3n<\/strong><br \/>\nLos aspirantes deber\u00e1n estar en posesi\u00f3n o reunir las condiciones para que les pueda ser expedida de la titulaci\u00f3n exigida para el desempe\u00f1o de puestos de interinidad o de otras <strong>titulaciones declaradas equivalentes a efectos de docencia recogidas en el anexo II<\/strong> de esta convocatoria.<\/p>\n<p style=\"text-align: justify;\"><strong> Las Tasas de inscripci\u00f3n ser\u00e1n de 38,15 \u20ac<\/strong>; Se aplicar\u00e1 una bonificaci\u00f3n\/reducci\u00f3n de la tasa a las personas que cumplan cualquiera de las condiciones indicadas en la convocatoria. El pago podr\u00e1 realizarse mediante cualquier tarjeta de cr\u00e9dito o d\u00e9bito emitida por Visa o Mastercard a trav\u00e9s de Internet en la direcci\u00f3n https:\/\/agenciatributaria.carm.es\/pasarelapagos. Para realizar el pago a trav\u00e9s de este medio no es necesario identificarse electr\u00f3nicamente ni disponer de ning\u00fan sistema de firma electr\u00f3nica.<\/p>\n<p style=\"text-align: justify;\">Art\u00edculo 5.4. Dentro de las limitaciones establecidas en la presente convocatoria, cuando se opte por m\u00e1s de una especialidad, s<strong>e cumplimentar\u00e1n tantas solicitudes como n\u00famero de especialidades por las que se participe<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Orden de 29 de mayo de 2020 de la Consejer\u00eda de Educaci\u00f3n y Cultura por la que se convoca procedimiento &#8230; <a title=\"BOLSA EXTRAORDINARIA &#8211; Convocatoria de procedimiento extraordinario para la selecci\u00f3n de personal interino para varias especialidades de Secundaria\" class=\"read-more\" href=\"https:\/\/sidimurcia.org\/index.php\/2020\/06\/13\/convocatoria-de-procedimiento-extraordinario-para-la-seleccion-de-personal-interino-varias-especialidades-de-secundaria\/\" aria-label=\"Leer m\u00e1s sobre BOLSA EXTRAORDINARIA &#8211; Convocatoria de procedimiento extraordinario para la selecci\u00f3n de personal interino para varias especialidades de Secundaria\">Leer mas<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,80],"tags":[],"class_list":["post-4469","post","type-post","status-publish","format-standard","hentry","category-bolsa-extraordinaria","category-convocatoria-bolsa-extraordinaria-carm"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BOLSA EXTRAORDINARIA - Convocatoria de procedimiento extraordinario para la selecci\u00f3n de personal interino para varias especialidades de Secundaria - SIDI<\/title>\n<meta name=\"description\" content=\"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sidimurcia.org\/index.php\/2020\/06\/13\/convocatoria-de-procedimiento-extraordinario-para-la-seleccion-de-personal-interino-varias-especialidades-de-secundaria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BOLSA EXTRAORDINARIA - Convocatoria de procedimiento extraordinario para la selecci\u00f3n de personal interino para varias especialidades de Secundaria - SIDI\" \/>\n<meta property=\"og:description\" content=\"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sidimurcia.org\/index.php\/2020\/06\/13\/convocatoria-de-procedimiento-extraordinario-para-la-seleccion-de-personal-interino-varias-especialidades-de-secundaria\/\" \/>\n<meta property=\"og:site_name\" content=\"SIDI\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-es.facebook.com\/sidi.sindicatodedocentes\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-13T07:36:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-19T11:35:21+00:00\" \/>\n<meta name=\"author\" content=\"Jose Luis Torrente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SIDIMURCIA\" \/>\n<meta name=\"twitter:site\" content=\"@SIDIMURCIA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jose Luis Torrente\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2020\\\/06\\\/13\\\/convocatoria-de-procedimiento-extraordinario-para-la-seleccion-de-personal-interino-varias-especialidades-de-secundaria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2020\\\/06\\\/13\\\/convocatoria-de-procedimiento-extraordinario-para-la-seleccion-de-personal-interino-varias-especialidades-de-secundaria\\\/\"},\"author\":{\"name\":\"Jose Luis Torrente\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/person\\\/3f3207f88fb267669a31f8f46f76f86c\"},\"headline\":\"BOLSA EXTRAORDINARIA &#8211; Convocatoria de procedimiento extraordinario para la selecci\u00f3n de personal interino para varias especialidades de Secundaria\",\"datePublished\":\"2020-06-13T07:36:49+00:00\",\"dateModified\":\"2020-10-19T11:35:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2020\\\/06\\\/13\\\/convocatoria-de-procedimiento-extraordinario-para-la-seleccion-de-personal-interino-varias-especialidades-de-secundaria\\\/\"},\"wordCount\":358,\"publisher\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#organization\"},\"articleSection\":[\"Bolsa Extraordinaria\",\"Murcia-Convocatoria\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2020\\\/06\\\/13\\\/convocatoria-de-procedimiento-extraordinario-para-la-seleccion-de-personal-interino-varias-especialidades-de-secundaria\\\/\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2020\\\/06\\\/13\\\/convocatoria-de-procedimiento-extraordinario-para-la-seleccion-de-personal-interino-varias-especialidades-de-secundaria\\\/\",\"name\":\"BOLSA EXTRAORDINARIA - Convocatoria de procedimiento extraordinario para la selecci\u00f3n de personal interino para varias especialidades de Secundaria - SIDI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#website\"},\"datePublished\":\"2020-06-13T07:36:49+00:00\",\"dateModified\":\"2020-10-19T11:35:21+00:00\",\"description\":\"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\\\/mes. Defendemos la educaci\u00f3n p\u00fablica.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2020\\\/06\\\/13\\\/convocatoria-de-procedimiento-extraordinario-para-la-seleccion-de-personal-interino-varias-especialidades-de-secundaria\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2020\\\/06\\\/13\\\/convocatoria-de-procedimiento-extraordinario-para-la-seleccion-de-personal-interino-varias-especialidades-de-secundaria\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2020\\\/06\\\/13\\\/convocatoria-de-procedimiento-extraordinario-para-la-seleccion-de-personal-interino-varias-especialidades-de-secundaria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sidimurcia.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BOLSA EXTRAORDINARIA &#8211; Convocatoria de procedimiento extraordinario para la selecci\u00f3n de personal interino para varias especialidades de Secundaria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#website\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/\",\"name\":\"SIDI\",\"description\":\"Sindicato Independiente de Docentes\",\"publisher\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sidimurcia.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#organization\",\"name\":\"Sindicato Independiente de Docentes - SIDI\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/wp-content\\\/uploads\\\/cropped-PARAPESTANAWEB-1.jpg\",\"contentUrl\":\"https:\\\/\\\/sidimurcia.org\\\/wp-content\\\/uploads\\\/cropped-PARAPESTANAWEB-1.jpg\",\"width\":512,\"height\":512,\"caption\":\"Sindicato Independiente de Docentes - SIDI\"},\"image\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-es.facebook.com\\\/sidi.sindicatodedocentes\",\"https:\\\/\\\/x.com\\\/SIDIMURCIA\",\"https:\\\/\\\/www.instagram.com\\\/sidi_murcia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCwwdL3uFtDKJdbOfmC70wIQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/person\\\/3f3207f88fb267669a31f8f46f76f86c\",\"name\":\"Jose Luis Torrente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g\",\"caption\":\"Jose Luis Torrente\"},\"url\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/author\\\/joseltorrente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BOLSA EXTRAORDINARIA - Convocatoria de procedimiento extraordinario para la selecci\u00f3n de personal interino para varias especialidades de Secundaria - SIDI","description":"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sidimurcia.org\/index.php\/2020\/06\/13\/convocatoria-de-procedimiento-extraordinario-para-la-seleccion-de-personal-interino-varias-especialidades-de-secundaria\/","og_locale":"es_ES","og_type":"article","og_title":"BOLSA EXTRAORDINARIA - Convocatoria de procedimiento extraordinario para la selecci\u00f3n de personal interino para varias especialidades de Secundaria - SIDI","og_description":"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.","og_url":"https:\/\/sidimurcia.org\/index.php\/2020\/06\/13\/convocatoria-de-procedimiento-extraordinario-para-la-seleccion-de-personal-interino-varias-especialidades-de-secundaria\/","og_site_name":"SIDI","article_publisher":"https:\/\/es-es.facebook.com\/sidi.sindicatodedocentes","article_published_time":"2020-06-13T07:36:49+00:00","article_modified_time":"2020-10-19T11:35:21+00:00","author":"Jose Luis Torrente","twitter_card":"summary_large_image","twitter_creator":"@SIDIMURCIA","twitter_site":"@SIDIMURCIA","twitter_misc":{"Escrito por":"Jose Luis Torrente","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sidimurcia.org\/index.php\/2020\/06\/13\/convocatoria-de-procedimiento-extraordinario-para-la-seleccion-de-personal-interino-varias-especialidades-de-secundaria\/#article","isPartOf":{"@id":"https:\/\/sidimurcia.org\/index.php\/2020\/06\/13\/convocatoria-de-procedimiento-extraordinario-para-la-seleccion-de-personal-interino-varias-especialidades-de-secundaria\/"},"author":{"name":"Jose Luis Torrente","@id":"https:\/\/sidimurcia.org\/#\/schema\/person\/3f3207f88fb267669a31f8f46f76f86c"},"headline":"BOLSA EXTRAORDINARIA &#8211; Convocatoria de procedimiento extraordinario para la selecci\u00f3n de personal interino para varias especialidades de Secundaria","datePublished":"2020-06-13T07:36:49+00:00","dateModified":"2020-10-19T11:35:21+00:00","mainEntityOfPage":{"@id":"https:\/\/sidimurcia.org\/index.php\/2020\/06\/13\/convocatoria-de-procedimiento-extraordinario-para-la-seleccion-de-personal-interino-varias-especialidades-de-secundaria\/"},"wordCount":358,"publisher":{"@id":"https:\/\/sidimurcia.org\/#organization"},"articleSection":["Bolsa Extraordinaria","Murcia-Convocatoria"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/sidimurcia.org\/index.php\/2020\/06\/13\/convocatoria-de-procedimiento-extraordinario-para-la-seleccion-de-personal-interino-varias-especialidades-de-secundaria\/","url":"https:\/\/sidimurcia.org\/index.php\/2020\/06\/13\/convocatoria-de-procedimiento-extraordinario-para-la-seleccion-de-personal-interino-varias-especialidades-de-secundaria\/","name":"BOLSA EXTRAORDINARIA - Convocatoria de procedimiento extraordinario para la selecci\u00f3n de personal interino para varias especialidades de Secundaria - SIDI","isPartOf":{"@id":"https:\/\/sidimurcia.org\/#website"},"datePublished":"2020-06-13T07:36:49+00:00","dateModified":"2020-10-19T11:35:21+00:00","description":"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.","breadcrumb":{"@id":"https:\/\/sidimurcia.org\/index.php\/2020\/06\/13\/convocatoria-de-procedimiento-extraordinario-para-la-seleccion-de-personal-interino-varias-especialidades-de-secundaria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sidimurcia.org\/index.php\/2020\/06\/13\/convocatoria-de-procedimiento-extraordinario-para-la-seleccion-de-personal-interino-varias-especialidades-de-secundaria\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sidimurcia.org\/index.php\/2020\/06\/13\/convocatoria-de-procedimiento-extraordinario-para-la-seleccion-de-personal-interino-varias-especialidades-de-secundaria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sidimurcia.org\/"},{"@type":"ListItem","position":2,"name":"BOLSA EXTRAORDINARIA &#8211; Convocatoria de procedimiento extraordinario para la selecci\u00f3n de personal interino para varias especialidades de Secundaria"}]},{"@type":"WebSite","@id":"https:\/\/sidimurcia.org\/#website","url":"https:\/\/sidimurcia.org\/","name":"SIDI","description":"Sindicato Independiente de Docentes","publisher":{"@id":"https:\/\/sidimurcia.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sidimurcia.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sidimurcia.org\/#organization","name":"Sindicato Independiente de Docentes - SIDI","url":"https:\/\/sidimurcia.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sidimurcia.org\/#\/schema\/logo\/image\/","url":"https:\/\/sidimurcia.org\/wp-content\/uploads\/cropped-PARAPESTANAWEB-1.jpg","contentUrl":"https:\/\/sidimurcia.org\/wp-content\/uploads\/cropped-PARAPESTANAWEB-1.jpg","width":512,"height":512,"caption":"Sindicato Independiente de Docentes - SIDI"},"image":{"@id":"https:\/\/sidimurcia.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-es.facebook.com\/sidi.sindicatodedocentes","https:\/\/x.com\/SIDIMURCIA","https:\/\/www.instagram.com\/sidi_murcia\/","https:\/\/www.youtube.com\/channel\/UCwwdL3uFtDKJdbOfmC70wIQ"]},{"@type":"Person","@id":"https:\/\/sidimurcia.org\/#\/schema\/person\/3f3207f88fb267669a31f8f46f76f86c","name":"Jose Luis Torrente","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g","caption":"Jose Luis Torrente"},"url":"https:\/\/sidimurcia.org\/index.php\/author\/joseltorrente\/"}]}},"_links":{"self":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/posts\/4469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/comments?post=4469"}],"version-history":[{"count":0,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/posts\/4469\/revisions"}],"wp:attachment":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/media?parent=4469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/categories?post=4469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/tags?post=4469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}