{"id":5079,"date":"2020-07-31T09:07:45","date_gmt":"2020-07-31T09:07:45","guid":{"rendered":"https:\/\/sidimurcia.org\/?p=5079"},"modified":"2020-07-31T09:44:23","modified_gmt":"2020-07-31T09:44:23","slug":"31-07-2020-sidi-informa-recursos-adicionales-de-profesorado-para-los-centros-publicos-con-motivo-del-covid_19","status":"publish","type":"post","link":"https:\/\/sidimurcia.org\/index.php\/2020\/07\/31\/31-07-2020-sidi-informa-recursos-adicionales-de-profesorado-para-los-centros-publicos-con-motivo-del-covid_19\/","title":{"rendered":"31\/07\/2020 SIDI INFORMA: Recursos adicionales de profesorado para los centros p\u00fablicos con motivo del COVID_19"},"content":{"rendered":"<p style=\"text-align: justify;\">Se ha informado a SIDI del borrador de los recursos adicionales de profesorado para los centros p\u00fablicos con motivo de la pandemia COVID_19; mientras la actividad lectiva sea presencial, se dotar\u00e1 a los centros de los siguientes recursos humanos:<br \/>\n&#8211; Un docente de la especialidad de educaci\u00f3n infantil a tiempo total a los CEIP y CEIBAS que\u00a0 tengan alguna unidad que sobrepase los 20 alumnos.<br \/>\n&#8211; Los IES y los IESO con 60 profesores (1200 horas de cupo) o menos dispondr\u00e1n de un docente adicional a media jornada.<br \/>\n&#8211; Los IES con m\u00e1s de 60 profesores (1200 horas de cupo) dispondr\u00e1n de un docente adicional a tiempo completo.<\/p>\n<p style=\"text-align: justify;\">Estos nombramientos se extender\u00e1n hasta el 23 de diciembre de 2020 y podr\u00e1 ser prorrogada por el tiempo necesario para mantener activas las medidas de prevenci\u00f3n frente COVID-19.<\/p>\n<p><span style=\"color: #800080;\"><strong>SIDI solicitar\u00e1 que dichas plazas se dupliquen en el texto definitivo.<\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se ha informado a SIDI del borrador de los recursos adicionales de profesorado para los centros p\u00fablicos con motivo de &#8230; <a title=\"31\/07\/2020 SIDI INFORMA: Recursos adicionales de profesorado para los centros p\u00fablicos con motivo del COVID_19\" class=\"read-more\" href=\"https:\/\/sidimurcia.org\/index.php\/2020\/07\/31\/31-07-2020-sidi-informa-recursos-adicionales-de-profesorado-para-los-centros-publicos-con-motivo-del-covid_19\/\" aria-label=\"Leer m\u00e1s sobre 31\/07\/2020 SIDI INFORMA: Recursos adicionales de profesorado para los centros p\u00fablicos con motivo del COVID_19\">Leer mas<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[73],"tags":[],"class_list":["post-5079","post","type-post","status-publish","format-standard","hentry","category-noticias-y-novedades"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>31\/07\/2020 SIDI INFORMA: Recursos adicionales de profesorado para los centros p\u00fablicos con motivo del COVID_19 - SIDI<\/title>\n<meta name=\"description\" content=\"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sidimurcia.org\/index.php\/2020\/07\/31\/31-07-2020-sidi-informa-recursos-adicionales-de-profesorado-para-los-centros-publicos-con-motivo-del-covid_19\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"31\/07\/2020 SIDI INFORMA: Recursos adicionales de profesorado para los centros p\u00fablicos con motivo del COVID_19 - SIDI\" \/>\n<meta property=\"og:description\" content=\"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sidimurcia.org\/index.php\/2020\/07\/31\/31-07-2020-sidi-informa-recursos-adicionales-de-profesorado-para-los-centros-publicos-con-motivo-del-covid_19\/\" \/>\n<meta property=\"og:site_name\" content=\"SIDI\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-es.facebook.com\/sidi.sindicatodedocentes\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-31T09:07:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-31T09:44:23+00:00\" \/>\n<meta name=\"author\" content=\"Jose Luis Torrente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SIDIMURCIA\" \/>\n<meta name=\"twitter:site\" content=\"@SIDIMURCIA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jose Luis Torrente\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2020\\\/07\\\/31\\\/31-07-2020-sidi-informa-recursos-adicionales-de-profesorado-para-los-centros-publicos-con-motivo-del-covid_19\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2020\\\/07\\\/31\\\/31-07-2020-sidi-informa-recursos-adicionales-de-profesorado-para-los-centros-publicos-con-motivo-del-covid_19\\\/\"},\"author\":{\"name\":\"Jose Luis Torrente\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/person\\\/3f3207f88fb267669a31f8f46f76f86c\"},\"headline\":\"31\\\/07\\\/2020 SIDI INFORMA: Recursos adicionales de profesorado para los centros p\u00fablicos con motivo del COVID_19\",\"datePublished\":\"2020-07-31T09:07:45+00:00\",\"dateModified\":\"2020-07-31T09:44:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2020\\\/07\\\/31\\\/31-07-2020-sidi-informa-recursos-adicionales-de-profesorado-para-los-centros-publicos-con-motivo-del-covid_19\\\/\"},\"wordCount\":162,\"publisher\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#organization\"},\"articleSection\":[\"Noticias y Novedades\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2020\\\/07\\\/31\\\/31-07-2020-sidi-informa-recursos-adicionales-de-profesorado-para-los-centros-publicos-con-motivo-del-covid_19\\\/\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2020\\\/07\\\/31\\\/31-07-2020-sidi-informa-recursos-adicionales-de-profesorado-para-los-centros-publicos-con-motivo-del-covid_19\\\/\",\"name\":\"31\\\/07\\\/2020 SIDI INFORMA: Recursos adicionales de profesorado para los centros p\u00fablicos con motivo del COVID_19 - SIDI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#website\"},\"datePublished\":\"2020-07-31T09:07:45+00:00\",\"dateModified\":\"2020-07-31T09:44:23+00:00\",\"description\":\"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\\\/mes. Defendemos la educaci\u00f3n p\u00fablica.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2020\\\/07\\\/31\\\/31-07-2020-sidi-informa-recursos-adicionales-de-profesorado-para-los-centros-publicos-con-motivo-del-covid_19\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2020\\\/07\\\/31\\\/31-07-2020-sidi-informa-recursos-adicionales-de-profesorado-para-los-centros-publicos-con-motivo-del-covid_19\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2020\\\/07\\\/31\\\/31-07-2020-sidi-informa-recursos-adicionales-de-profesorado-para-los-centros-publicos-con-motivo-del-covid_19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sidimurcia.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"31\\\/07\\\/2020 SIDI INFORMA: Recursos adicionales de profesorado para los centros p\u00fablicos con motivo del COVID_19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#website\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/\",\"name\":\"SIDI\",\"description\":\"Sindicato Independiente de Docentes\",\"publisher\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sidimurcia.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#organization\",\"name\":\"Sindicato Independiente de Docentes - SIDI\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/wp-content\\\/uploads\\\/cropped-PARAPESTANAWEB-1.jpg\",\"contentUrl\":\"https:\\\/\\\/sidimurcia.org\\\/wp-content\\\/uploads\\\/cropped-PARAPESTANAWEB-1.jpg\",\"width\":512,\"height\":512,\"caption\":\"Sindicato Independiente de Docentes - SIDI\"},\"image\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-es.facebook.com\\\/sidi.sindicatodedocentes\",\"https:\\\/\\\/x.com\\\/SIDIMURCIA\",\"https:\\\/\\\/www.instagram.com\\\/sidi_murcia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCwwdL3uFtDKJdbOfmC70wIQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/person\\\/3f3207f88fb267669a31f8f46f76f86c\",\"name\":\"Jose Luis Torrente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g\",\"caption\":\"Jose Luis Torrente\"},\"url\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/author\\\/joseltorrente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"31\/07\/2020 SIDI INFORMA: Recursos adicionales de profesorado para los centros p\u00fablicos con motivo del COVID_19 - SIDI","description":"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sidimurcia.org\/index.php\/2020\/07\/31\/31-07-2020-sidi-informa-recursos-adicionales-de-profesorado-para-los-centros-publicos-con-motivo-del-covid_19\/","og_locale":"es_ES","og_type":"article","og_title":"31\/07\/2020 SIDI INFORMA: Recursos adicionales de profesorado para los centros p\u00fablicos con motivo del COVID_19 - SIDI","og_description":"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.","og_url":"https:\/\/sidimurcia.org\/index.php\/2020\/07\/31\/31-07-2020-sidi-informa-recursos-adicionales-de-profesorado-para-los-centros-publicos-con-motivo-del-covid_19\/","og_site_name":"SIDI","article_publisher":"https:\/\/es-es.facebook.com\/sidi.sindicatodedocentes","article_published_time":"2020-07-31T09:07:45+00:00","article_modified_time":"2020-07-31T09:44:23+00:00","author":"Jose Luis Torrente","twitter_card":"summary_large_image","twitter_creator":"@SIDIMURCIA","twitter_site":"@SIDIMURCIA","twitter_misc":{"Escrito por":"Jose Luis Torrente","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sidimurcia.org\/index.php\/2020\/07\/31\/31-07-2020-sidi-informa-recursos-adicionales-de-profesorado-para-los-centros-publicos-con-motivo-del-covid_19\/#article","isPartOf":{"@id":"https:\/\/sidimurcia.org\/index.php\/2020\/07\/31\/31-07-2020-sidi-informa-recursos-adicionales-de-profesorado-para-los-centros-publicos-con-motivo-del-covid_19\/"},"author":{"name":"Jose Luis Torrente","@id":"https:\/\/sidimurcia.org\/#\/schema\/person\/3f3207f88fb267669a31f8f46f76f86c"},"headline":"31\/07\/2020 SIDI INFORMA: Recursos adicionales de profesorado para los centros p\u00fablicos con motivo del COVID_19","datePublished":"2020-07-31T09:07:45+00:00","dateModified":"2020-07-31T09:44:23+00:00","mainEntityOfPage":{"@id":"https:\/\/sidimurcia.org\/index.php\/2020\/07\/31\/31-07-2020-sidi-informa-recursos-adicionales-de-profesorado-para-los-centros-publicos-con-motivo-del-covid_19\/"},"wordCount":162,"publisher":{"@id":"https:\/\/sidimurcia.org\/#organization"},"articleSection":["Noticias y Novedades"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/sidimurcia.org\/index.php\/2020\/07\/31\/31-07-2020-sidi-informa-recursos-adicionales-de-profesorado-para-los-centros-publicos-con-motivo-del-covid_19\/","url":"https:\/\/sidimurcia.org\/index.php\/2020\/07\/31\/31-07-2020-sidi-informa-recursos-adicionales-de-profesorado-para-los-centros-publicos-con-motivo-del-covid_19\/","name":"31\/07\/2020 SIDI INFORMA: Recursos adicionales de profesorado para los centros p\u00fablicos con motivo del COVID_19 - SIDI","isPartOf":{"@id":"https:\/\/sidimurcia.org\/#website"},"datePublished":"2020-07-31T09:07:45+00:00","dateModified":"2020-07-31T09:44:23+00:00","description":"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.","breadcrumb":{"@id":"https:\/\/sidimurcia.org\/index.php\/2020\/07\/31\/31-07-2020-sidi-informa-recursos-adicionales-de-profesorado-para-los-centros-publicos-con-motivo-del-covid_19\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sidimurcia.org\/index.php\/2020\/07\/31\/31-07-2020-sidi-informa-recursos-adicionales-de-profesorado-para-los-centros-publicos-con-motivo-del-covid_19\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sidimurcia.org\/index.php\/2020\/07\/31\/31-07-2020-sidi-informa-recursos-adicionales-de-profesorado-para-los-centros-publicos-con-motivo-del-covid_19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sidimurcia.org\/"},{"@type":"ListItem","position":2,"name":"31\/07\/2020 SIDI INFORMA: Recursos adicionales de profesorado para los centros p\u00fablicos con motivo del COVID_19"}]},{"@type":"WebSite","@id":"https:\/\/sidimurcia.org\/#website","url":"https:\/\/sidimurcia.org\/","name":"SIDI","description":"Sindicato Independiente de Docentes","publisher":{"@id":"https:\/\/sidimurcia.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sidimurcia.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sidimurcia.org\/#organization","name":"Sindicato Independiente de Docentes - SIDI","url":"https:\/\/sidimurcia.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sidimurcia.org\/#\/schema\/logo\/image\/","url":"https:\/\/sidimurcia.org\/wp-content\/uploads\/cropped-PARAPESTANAWEB-1.jpg","contentUrl":"https:\/\/sidimurcia.org\/wp-content\/uploads\/cropped-PARAPESTANAWEB-1.jpg","width":512,"height":512,"caption":"Sindicato Independiente de Docentes - SIDI"},"image":{"@id":"https:\/\/sidimurcia.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-es.facebook.com\/sidi.sindicatodedocentes","https:\/\/x.com\/SIDIMURCIA","https:\/\/www.instagram.com\/sidi_murcia\/","https:\/\/www.youtube.com\/channel\/UCwwdL3uFtDKJdbOfmC70wIQ"]},{"@type":"Person","@id":"https:\/\/sidimurcia.org\/#\/schema\/person\/3f3207f88fb267669a31f8f46f76f86c","name":"Jose Luis Torrente","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g","caption":"Jose Luis Torrente"},"url":"https:\/\/sidimurcia.org\/index.php\/author\/joseltorrente\/"}]}},"_links":{"self":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/posts\/5079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/comments?post=5079"}],"version-history":[{"count":0,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/posts\/5079\/revisions"}],"wp:attachment":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/media?parent=5079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/categories?post=5079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/tags?post=5079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}