{"id":5944,"date":"2020-10-21T06:54:04","date_gmt":"2020-10-21T06:54:04","guid":{"rendered":"https:\/\/sidimurcia.org\/?p=5944"},"modified":"2020-10-21T06:54:04","modified_gmt":"2020-10-21T06:54:04","slug":"seleccion-definitiva-de-proyectos-de-formacion-en-centros-seminarios-de-equipo-docentes-y-grupos-trabajo-20-21","status":"publish","type":"post","link":"https:\/\/sidimurcia.org\/index.php\/2020\/10\/21\/seleccion-definitiva-de-proyectos-de-formacion-en-centros-seminarios-de-equipo-docentes-y-grupos-trabajo-20-21\/","title":{"rendered":"Selecci\u00f3n DEFINITIVA de Proyectos de Formaci\u00f3n en centros, seminarios de equipo docentes y grupos trabajo, 20\/21"},"content":{"rendered":"<ul>\n<li style=\"text-align: justify;\"><a class=\"enlaceMarron\" title=\"Resoluci\u00f3n del Director General de Planificaci\u00f3n Educativa y Recursos Humanos por la que se realiza la selecci\u00f3n de proyectos de formaci\u00f3n en centros, seminarios de equipos docentes y grupos de trabajo para el curso 2020-21, realizada de acuerdo con lo establecido en la Orden de 25 de julio de 2016 de la Consejer\u00eda de Educaci\u00f3n y Universidades, por la que se regulan las modalidades de Formaci\u00f3n Aut\u00f3noma del Profesorado de la Regi\u00f3n de Murcia.\" href=\"http:\/\/servicios.educarm.es\/templates\/portal\/ficheros\/websDinamicas\/45\/Res def proyec form autonom prof en centr -semin-grupos CI302951 21-10-20.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Resoluci\u00f3n del Director General de Planificaci\u00f3n Educativa y Recursos Humanos por la que se realiza la selecci\u00f3n de proyectos de formaci\u00f3n en centros, seminarios de equipos docentes y grupos de trabajo para el curso 2020-21, realizada de acuerdo con lo establecido en la Orden de 25 de julio de 2016 de la Consejer\u00eda de Educaci\u00f3n y Universidades, por la que se regulan las modalidades de Formaci\u00f3n Aut\u00f3noma del Profesorado de la Regi\u00f3n de Murcia.<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Resoluci\u00f3n del Director General de Planificaci\u00f3n Educativa y Recursos Humanos por la que se realiza la selecci\u00f3n de proyectos de &#8230; <a title=\"Selecci\u00f3n DEFINITIVA de Proyectos de Formaci\u00f3n en centros, seminarios de equipo docentes y grupos trabajo, 20\/21\" class=\"read-more\" href=\"https:\/\/sidimurcia.org\/index.php\/2020\/10\/21\/seleccion-definitiva-de-proyectos-de-formacion-en-centros-seminarios-de-equipo-docentes-y-grupos-trabajo-20-21\/\" aria-label=\"Leer m\u00e1s sobre Selecci\u00f3n DEFINITIVA de Proyectos de Formaci\u00f3n en centros, seminarios de equipo docentes y grupos trabajo, 20\/21\">Leer mas<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[74],"tags":[],"class_list":["post-5944","post","type-post","status-publish","format-standard","hentry","category-formacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Selecci\u00f3n DEFINITIVA de Proyectos de Formaci\u00f3n en centros, seminarios de equipo docentes y grupos trabajo, 20\/21 - SIDI<\/title>\n<meta name=\"description\" content=\"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sidimurcia.org\/index.php\/2020\/10\/21\/seleccion-definitiva-de-proyectos-de-formacion-en-centros-seminarios-de-equipo-docentes-y-grupos-trabajo-20-21\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Selecci\u00f3n DEFINITIVA de Proyectos de Formaci\u00f3n en centros, seminarios de equipo docentes y grupos trabajo, 20\/21 - SIDI\" \/>\n<meta property=\"og:description\" content=\"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sidimurcia.org\/index.php\/2020\/10\/21\/seleccion-definitiva-de-proyectos-de-formacion-en-centros-seminarios-de-equipo-docentes-y-grupos-trabajo-20-21\/\" \/>\n<meta property=\"og:site_name\" content=\"SIDI\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-es.facebook.com\/sidi.sindicatodedocentes\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-21T06:54:04+00:00\" \/>\n<meta name=\"author\" content=\"Jose Luis Torrente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SIDIMURCIA\" \/>\n<meta name=\"twitter:site\" content=\"@SIDIMURCIA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jose Luis Torrente\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2020\\\/10\\\/21\\\/seleccion-definitiva-de-proyectos-de-formacion-en-centros-seminarios-de-equipo-docentes-y-grupos-trabajo-20-21\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2020\\\/10\\\/21\\\/seleccion-definitiva-de-proyectos-de-formacion-en-centros-seminarios-de-equipo-docentes-y-grupos-trabajo-20-21\\\/\"},\"author\":{\"name\":\"Jose Luis Torrente\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/person\\\/3f3207f88fb267669a31f8f46f76f86c\"},\"headline\":\"Selecci\u00f3n DEFINITIVA de Proyectos de Formaci\u00f3n en centros, seminarios de equipo docentes y grupos trabajo, 20\\\/21\",\"datePublished\":\"2020-10-21T06:54:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2020\\\/10\\\/21\\\/seleccion-definitiva-de-proyectos-de-formacion-en-centros-seminarios-de-equipo-docentes-y-grupos-trabajo-20-21\\\/\"},\"wordCount\":98,\"publisher\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#organization\"},\"articleSection\":[\"Formaci\u00f3n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2020\\\/10\\\/21\\\/seleccion-definitiva-de-proyectos-de-formacion-en-centros-seminarios-de-equipo-docentes-y-grupos-trabajo-20-21\\\/\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2020\\\/10\\\/21\\\/seleccion-definitiva-de-proyectos-de-formacion-en-centros-seminarios-de-equipo-docentes-y-grupos-trabajo-20-21\\\/\",\"name\":\"Selecci\u00f3n DEFINITIVA de Proyectos de Formaci\u00f3n en centros, seminarios de equipo docentes y grupos trabajo, 20\\\/21 - SIDI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#website\"},\"datePublished\":\"2020-10-21T06:54:04+00:00\",\"description\":\"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\\\/mes. Defendemos la educaci\u00f3n p\u00fablica.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2020\\\/10\\\/21\\\/seleccion-definitiva-de-proyectos-de-formacion-en-centros-seminarios-de-equipo-docentes-y-grupos-trabajo-20-21\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2020\\\/10\\\/21\\\/seleccion-definitiva-de-proyectos-de-formacion-en-centros-seminarios-de-equipo-docentes-y-grupos-trabajo-20-21\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2020\\\/10\\\/21\\\/seleccion-definitiva-de-proyectos-de-formacion-en-centros-seminarios-de-equipo-docentes-y-grupos-trabajo-20-21\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sidimurcia.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Selecci\u00f3n DEFINITIVA de Proyectos de Formaci\u00f3n en centros, seminarios de equipo docentes y grupos trabajo, 20\\\/21\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#website\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/\",\"name\":\"SIDI\",\"description\":\"Sindicato Independiente de Docentes\",\"publisher\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sidimurcia.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#organization\",\"name\":\"Sindicato Independiente de Docentes - SIDI\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/wp-content\\\/uploads\\\/cropped-PARAPESTANAWEB-1.jpg\",\"contentUrl\":\"https:\\\/\\\/sidimurcia.org\\\/wp-content\\\/uploads\\\/cropped-PARAPESTANAWEB-1.jpg\",\"width\":512,\"height\":512,\"caption\":\"Sindicato Independiente de Docentes - SIDI\"},\"image\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-es.facebook.com\\\/sidi.sindicatodedocentes\",\"https:\\\/\\\/x.com\\\/SIDIMURCIA\",\"https:\\\/\\\/www.instagram.com\\\/sidi_murcia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCwwdL3uFtDKJdbOfmC70wIQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/person\\\/3f3207f88fb267669a31f8f46f76f86c\",\"name\":\"Jose Luis Torrente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g\",\"caption\":\"Jose Luis Torrente\"},\"url\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/author\\\/joseltorrente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Selecci\u00f3n DEFINITIVA de Proyectos de Formaci\u00f3n en centros, seminarios de equipo docentes y grupos trabajo, 20\/21 - SIDI","description":"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sidimurcia.org\/index.php\/2020\/10\/21\/seleccion-definitiva-de-proyectos-de-formacion-en-centros-seminarios-de-equipo-docentes-y-grupos-trabajo-20-21\/","og_locale":"es_ES","og_type":"article","og_title":"Selecci\u00f3n DEFINITIVA de Proyectos de Formaci\u00f3n en centros, seminarios de equipo docentes y grupos trabajo, 20\/21 - SIDI","og_description":"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.","og_url":"https:\/\/sidimurcia.org\/index.php\/2020\/10\/21\/seleccion-definitiva-de-proyectos-de-formacion-en-centros-seminarios-de-equipo-docentes-y-grupos-trabajo-20-21\/","og_site_name":"SIDI","article_publisher":"https:\/\/es-es.facebook.com\/sidi.sindicatodedocentes","article_published_time":"2020-10-21T06:54:04+00:00","author":"Jose Luis Torrente","twitter_card":"summary_large_image","twitter_creator":"@SIDIMURCIA","twitter_site":"@SIDIMURCIA","twitter_misc":{"Escrito por":"Jose Luis Torrente"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sidimurcia.org\/index.php\/2020\/10\/21\/seleccion-definitiva-de-proyectos-de-formacion-en-centros-seminarios-de-equipo-docentes-y-grupos-trabajo-20-21\/#article","isPartOf":{"@id":"https:\/\/sidimurcia.org\/index.php\/2020\/10\/21\/seleccion-definitiva-de-proyectos-de-formacion-en-centros-seminarios-de-equipo-docentes-y-grupos-trabajo-20-21\/"},"author":{"name":"Jose Luis Torrente","@id":"https:\/\/sidimurcia.org\/#\/schema\/person\/3f3207f88fb267669a31f8f46f76f86c"},"headline":"Selecci\u00f3n DEFINITIVA de Proyectos de Formaci\u00f3n en centros, seminarios de equipo docentes y grupos trabajo, 20\/21","datePublished":"2020-10-21T06:54:04+00:00","mainEntityOfPage":{"@id":"https:\/\/sidimurcia.org\/index.php\/2020\/10\/21\/seleccion-definitiva-de-proyectos-de-formacion-en-centros-seminarios-de-equipo-docentes-y-grupos-trabajo-20-21\/"},"wordCount":98,"publisher":{"@id":"https:\/\/sidimurcia.org\/#organization"},"articleSection":["Formaci\u00f3n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/sidimurcia.org\/index.php\/2020\/10\/21\/seleccion-definitiva-de-proyectos-de-formacion-en-centros-seminarios-de-equipo-docentes-y-grupos-trabajo-20-21\/","url":"https:\/\/sidimurcia.org\/index.php\/2020\/10\/21\/seleccion-definitiva-de-proyectos-de-formacion-en-centros-seminarios-de-equipo-docentes-y-grupos-trabajo-20-21\/","name":"Selecci\u00f3n DEFINITIVA de Proyectos de Formaci\u00f3n en centros, seminarios de equipo docentes y grupos trabajo, 20\/21 - SIDI","isPartOf":{"@id":"https:\/\/sidimurcia.org\/#website"},"datePublished":"2020-10-21T06:54:04+00:00","description":"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.","breadcrumb":{"@id":"https:\/\/sidimurcia.org\/index.php\/2020\/10\/21\/seleccion-definitiva-de-proyectos-de-formacion-en-centros-seminarios-de-equipo-docentes-y-grupos-trabajo-20-21\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sidimurcia.org\/index.php\/2020\/10\/21\/seleccion-definitiva-de-proyectos-de-formacion-en-centros-seminarios-de-equipo-docentes-y-grupos-trabajo-20-21\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sidimurcia.org\/index.php\/2020\/10\/21\/seleccion-definitiva-de-proyectos-de-formacion-en-centros-seminarios-de-equipo-docentes-y-grupos-trabajo-20-21\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sidimurcia.org\/"},{"@type":"ListItem","position":2,"name":"Selecci\u00f3n DEFINITIVA de Proyectos de Formaci\u00f3n en centros, seminarios de equipo docentes y grupos trabajo, 20\/21"}]},{"@type":"WebSite","@id":"https:\/\/sidimurcia.org\/#website","url":"https:\/\/sidimurcia.org\/","name":"SIDI","description":"Sindicato Independiente de Docentes","publisher":{"@id":"https:\/\/sidimurcia.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sidimurcia.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sidimurcia.org\/#organization","name":"Sindicato Independiente de Docentes - SIDI","url":"https:\/\/sidimurcia.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sidimurcia.org\/#\/schema\/logo\/image\/","url":"https:\/\/sidimurcia.org\/wp-content\/uploads\/cropped-PARAPESTANAWEB-1.jpg","contentUrl":"https:\/\/sidimurcia.org\/wp-content\/uploads\/cropped-PARAPESTANAWEB-1.jpg","width":512,"height":512,"caption":"Sindicato Independiente de Docentes - SIDI"},"image":{"@id":"https:\/\/sidimurcia.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-es.facebook.com\/sidi.sindicatodedocentes","https:\/\/x.com\/SIDIMURCIA","https:\/\/www.instagram.com\/sidi_murcia\/","https:\/\/www.youtube.com\/channel\/UCwwdL3uFtDKJdbOfmC70wIQ"]},{"@type":"Person","@id":"https:\/\/sidimurcia.org\/#\/schema\/person\/3f3207f88fb267669a31f8f46f76f86c","name":"Jose Luis Torrente","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g","caption":"Jose Luis Torrente"},"url":"https:\/\/sidimurcia.org\/index.php\/author\/joseltorrente\/"}]}},"_links":{"self":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/posts\/5944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/comments?post=5944"}],"version-history":[{"count":0,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/posts\/5944\/revisions"}],"wp:attachment":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/media?parent=5944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/categories?post=5944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/tags?post=5944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}