{"id":7376,"date":"2021-01-18T07:48:04","date_gmt":"2021-01-18T07:48:04","guid":{"rendered":"https:\/\/sidimurcia.org\/?p=7376"},"modified":"2021-01-26T09:24:02","modified_gmt":"2021-01-26T09:24:02","slug":"orden-de-15-01-2021-que-modifica-la-orden-12-02-19-bases-de-procedimientos-selectivos-para-ingreso-a-nuevas-especialidades-docentes-carm","status":"publish","type":"post","link":"https:\/\/sidimurcia.org\/index.php\/2021\/01\/18\/orden-de-15-01-2021-que-modifica-la-orden-12-02-19-bases-de-procedimientos-selectivos-para-ingreso-a-nuevas-especialidades-docentes-carm\/","title":{"rendered":"Orden de 15\/01\/2021 que modifica la Orden 12\/02\/19 Bases de Procedimientos Selectivos para ingreso a nuevas Especialidades Docentes CARM"},"content":{"rendered":"<ul>\n<li style=\"text-align: justify;\"><a href=\"http:\/\/servicios.educarm.es\/templates\/portal\/ficheros\/websDinamicas\/45\/241%20Modif%20bases%20reguladoras%20BORM%2018-1-21.pdf\">Orden de 15 de enero de 2021 de la Consejer\u00eda de Educaci\u00f3n y Cultura por la que se modifica la Orden de 12 de febrero de 2019, por la que se regulan las bases de los procedimientos selectivos para el ingreso, acceso y adquisici\u00f3n de nuevas especialidades en los cuerpos de funcionarios docentes no universitarios a que se refiere la Ley Org\u00e1nica 2\/2006, de 3 de mayo, de educaci\u00f3n, excepto en los Cuerpos de Catedr\u00e1ticos y en el Cuerpo de Inspectores de Educaci\u00f3n; y la composici\u00f3n de la lista de interinidad derivada de dichos procedimientos, en el \u00e1mbito de gesti\u00f3n de la Comunidad Aut\u00f3noma de la Regi\u00f3n de Murcia<\/a><\/li>\n<\/ul>\n<p><a href=\"https:\/\/sidimurcia.org\/sd\/index2.php?option=com_content&amp;task=view&amp;id=13103&amp;Itemid=39\">Orden 12\/02\/19 Bases de Procedimientos Selectivos para ingreso a nuevas Especialidades Docentes CARM<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Orden de 15 de enero de 2021 de la Consejer\u00eda de Educaci\u00f3n y Cultura por la que se modifica la &#8230; <a title=\"Orden de 15\/01\/2021 que modifica la Orden 12\/02\/19 Bases de Procedimientos Selectivos para ingreso a nuevas Especialidades Docentes CARM\" class=\"read-more\" href=\"https:\/\/sidimurcia.org\/index.php\/2021\/01\/18\/orden-de-15-01-2021-que-modifica-la-orden-12-02-19-bases-de-procedimientos-selectivos-para-ingreso-a-nuevas-especialidades-docentes-carm\/\" aria-label=\"Leer m\u00e1s sobre Orden de 15\/01\/2021 que modifica la Orden 12\/02\/19 Bases de Procedimientos Selectivos para ingreso a nuevas Especialidades Docentes CARM\">Leer mas<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43,85],"tags":[],"class_list":["post-7376","post","type-post","status-publish","format-standard","hentry","category-oposiciones","category-oposiciones-2021"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Orden de 15\/01\/2021 que modifica la Orden 12\/02\/19 Bases de Procedimientos Selectivos para ingreso a nuevas Especialidades Docentes CARM - SIDI<\/title>\n<meta name=\"description\" content=\"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sidimurcia.org\/index.php\/2021\/01\/18\/orden-de-15-01-2021-que-modifica-la-orden-12-02-19-bases-de-procedimientos-selectivos-para-ingreso-a-nuevas-especialidades-docentes-carm\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Orden de 15\/01\/2021 que modifica la Orden 12\/02\/19 Bases de Procedimientos Selectivos para ingreso a nuevas Especialidades Docentes CARM - SIDI\" \/>\n<meta property=\"og:description\" content=\"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sidimurcia.org\/index.php\/2021\/01\/18\/orden-de-15-01-2021-que-modifica-la-orden-12-02-19-bases-de-procedimientos-selectivos-para-ingreso-a-nuevas-especialidades-docentes-carm\/\" \/>\n<meta property=\"og:site_name\" content=\"SIDI\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-es.facebook.com\/sidi.sindicatodedocentes\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-18T07:48:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-26T09:24:02+00:00\" \/>\n<meta name=\"author\" content=\"Jose Luis Torrente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SIDIMURCIA\" \/>\n<meta name=\"twitter:site\" content=\"@SIDIMURCIA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jose Luis Torrente\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2021\\\/01\\\/18\\\/orden-de-15-01-2021-que-modifica-la-orden-12-02-19-bases-de-procedimientos-selectivos-para-ingreso-a-nuevas-especialidades-docentes-carm\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2021\\\/01\\\/18\\\/orden-de-15-01-2021-que-modifica-la-orden-12-02-19-bases-de-procedimientos-selectivos-para-ingreso-a-nuevas-especialidades-docentes-carm\\\/\"},\"author\":{\"name\":\"Jose Luis Torrente\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/person\\\/3f3207f88fb267669a31f8f46f76f86c\"},\"headline\":\"Orden de 15\\\/01\\\/2021 que modifica la Orden 12\\\/02\\\/19 Bases de Procedimientos Selectivos para ingreso a nuevas Especialidades Docentes CARM\",\"datePublished\":\"2021-01-18T07:48:04+00:00\",\"dateModified\":\"2021-01-26T09:24:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2021\\\/01\\\/18\\\/orden-de-15-01-2021-que-modifica-la-orden-12-02-19-bases-de-procedimientos-selectivos-para-ingreso-a-nuevas-especialidades-docentes-carm\\\/\"},\"wordCount\":143,\"publisher\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#organization\"},\"articleSection\":[\"Oposiciones\",\"Oposiciones 2021\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2021\\\/01\\\/18\\\/orden-de-15-01-2021-que-modifica-la-orden-12-02-19-bases-de-procedimientos-selectivos-para-ingreso-a-nuevas-especialidades-docentes-carm\\\/\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2021\\\/01\\\/18\\\/orden-de-15-01-2021-que-modifica-la-orden-12-02-19-bases-de-procedimientos-selectivos-para-ingreso-a-nuevas-especialidades-docentes-carm\\\/\",\"name\":\"Orden de 15\\\/01\\\/2021 que modifica la Orden 12\\\/02\\\/19 Bases de Procedimientos Selectivos para ingreso a nuevas Especialidades Docentes CARM - SIDI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#website\"},\"datePublished\":\"2021-01-18T07:48:04+00:00\",\"dateModified\":\"2021-01-26T09:24:02+00:00\",\"description\":\"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\\\/mes. Defendemos la educaci\u00f3n p\u00fablica.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2021\\\/01\\\/18\\\/orden-de-15-01-2021-que-modifica-la-orden-12-02-19-bases-de-procedimientos-selectivos-para-ingreso-a-nuevas-especialidades-docentes-carm\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2021\\\/01\\\/18\\\/orden-de-15-01-2021-que-modifica-la-orden-12-02-19-bases-de-procedimientos-selectivos-para-ingreso-a-nuevas-especialidades-docentes-carm\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2021\\\/01\\\/18\\\/orden-de-15-01-2021-que-modifica-la-orden-12-02-19-bases-de-procedimientos-selectivos-para-ingreso-a-nuevas-especialidades-docentes-carm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sidimurcia.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Orden de 15\\\/01\\\/2021 que modifica la Orden 12\\\/02\\\/19 Bases de Procedimientos Selectivos para ingreso a nuevas Especialidades Docentes CARM\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#website\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/\",\"name\":\"SIDI\",\"description\":\"Sindicato Independiente de Docentes\",\"publisher\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sidimurcia.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#organization\",\"name\":\"Sindicato Independiente de Docentes - SIDI\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/wp-content\\\/uploads\\\/cropped-PARAPESTANAWEB-1.jpg\",\"contentUrl\":\"https:\\\/\\\/sidimurcia.org\\\/wp-content\\\/uploads\\\/cropped-PARAPESTANAWEB-1.jpg\",\"width\":512,\"height\":512,\"caption\":\"Sindicato Independiente de Docentes - SIDI\"},\"image\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-es.facebook.com\\\/sidi.sindicatodedocentes\",\"https:\\\/\\\/x.com\\\/SIDIMURCIA\",\"https:\\\/\\\/www.instagram.com\\\/sidi_murcia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCwwdL3uFtDKJdbOfmC70wIQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/person\\\/3f3207f88fb267669a31f8f46f76f86c\",\"name\":\"Jose Luis Torrente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g\",\"caption\":\"Jose Luis Torrente\"},\"url\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/author\\\/joseltorrente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Orden de 15\/01\/2021 que modifica la Orden 12\/02\/19 Bases de Procedimientos Selectivos para ingreso a nuevas Especialidades Docentes CARM - SIDI","description":"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sidimurcia.org\/index.php\/2021\/01\/18\/orden-de-15-01-2021-que-modifica-la-orden-12-02-19-bases-de-procedimientos-selectivos-para-ingreso-a-nuevas-especialidades-docentes-carm\/","og_locale":"es_ES","og_type":"article","og_title":"Orden de 15\/01\/2021 que modifica la Orden 12\/02\/19 Bases de Procedimientos Selectivos para ingreso a nuevas Especialidades Docentes CARM - SIDI","og_description":"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.","og_url":"https:\/\/sidimurcia.org\/index.php\/2021\/01\/18\/orden-de-15-01-2021-que-modifica-la-orden-12-02-19-bases-de-procedimientos-selectivos-para-ingreso-a-nuevas-especialidades-docentes-carm\/","og_site_name":"SIDI","article_publisher":"https:\/\/es-es.facebook.com\/sidi.sindicatodedocentes","article_published_time":"2021-01-18T07:48:04+00:00","article_modified_time":"2021-01-26T09:24:02+00:00","author":"Jose Luis Torrente","twitter_card":"summary_large_image","twitter_creator":"@SIDIMURCIA","twitter_site":"@SIDIMURCIA","twitter_misc":{"Escrito por":"Jose Luis Torrente","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sidimurcia.org\/index.php\/2021\/01\/18\/orden-de-15-01-2021-que-modifica-la-orden-12-02-19-bases-de-procedimientos-selectivos-para-ingreso-a-nuevas-especialidades-docentes-carm\/#article","isPartOf":{"@id":"https:\/\/sidimurcia.org\/index.php\/2021\/01\/18\/orden-de-15-01-2021-que-modifica-la-orden-12-02-19-bases-de-procedimientos-selectivos-para-ingreso-a-nuevas-especialidades-docentes-carm\/"},"author":{"name":"Jose Luis Torrente","@id":"https:\/\/sidimurcia.org\/#\/schema\/person\/3f3207f88fb267669a31f8f46f76f86c"},"headline":"Orden de 15\/01\/2021 que modifica la Orden 12\/02\/19 Bases de Procedimientos Selectivos para ingreso a nuevas Especialidades Docentes CARM","datePublished":"2021-01-18T07:48:04+00:00","dateModified":"2021-01-26T09:24:02+00:00","mainEntityOfPage":{"@id":"https:\/\/sidimurcia.org\/index.php\/2021\/01\/18\/orden-de-15-01-2021-que-modifica-la-orden-12-02-19-bases-de-procedimientos-selectivos-para-ingreso-a-nuevas-especialidades-docentes-carm\/"},"wordCount":143,"publisher":{"@id":"https:\/\/sidimurcia.org\/#organization"},"articleSection":["Oposiciones","Oposiciones 2021"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/sidimurcia.org\/index.php\/2021\/01\/18\/orden-de-15-01-2021-que-modifica-la-orden-12-02-19-bases-de-procedimientos-selectivos-para-ingreso-a-nuevas-especialidades-docentes-carm\/","url":"https:\/\/sidimurcia.org\/index.php\/2021\/01\/18\/orden-de-15-01-2021-que-modifica-la-orden-12-02-19-bases-de-procedimientos-selectivos-para-ingreso-a-nuevas-especialidades-docentes-carm\/","name":"Orden de 15\/01\/2021 que modifica la Orden 12\/02\/19 Bases de Procedimientos Selectivos para ingreso a nuevas Especialidades Docentes CARM - SIDI","isPartOf":{"@id":"https:\/\/sidimurcia.org\/#website"},"datePublished":"2021-01-18T07:48:04+00:00","dateModified":"2021-01-26T09:24:02+00:00","description":"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.","breadcrumb":{"@id":"https:\/\/sidimurcia.org\/index.php\/2021\/01\/18\/orden-de-15-01-2021-que-modifica-la-orden-12-02-19-bases-de-procedimientos-selectivos-para-ingreso-a-nuevas-especialidades-docentes-carm\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sidimurcia.org\/index.php\/2021\/01\/18\/orden-de-15-01-2021-que-modifica-la-orden-12-02-19-bases-de-procedimientos-selectivos-para-ingreso-a-nuevas-especialidades-docentes-carm\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sidimurcia.org\/index.php\/2021\/01\/18\/orden-de-15-01-2021-que-modifica-la-orden-12-02-19-bases-de-procedimientos-selectivos-para-ingreso-a-nuevas-especialidades-docentes-carm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sidimurcia.org\/"},{"@type":"ListItem","position":2,"name":"Orden de 15\/01\/2021 que modifica la Orden 12\/02\/19 Bases de Procedimientos Selectivos para ingreso a nuevas Especialidades Docentes CARM"}]},{"@type":"WebSite","@id":"https:\/\/sidimurcia.org\/#website","url":"https:\/\/sidimurcia.org\/","name":"SIDI","description":"Sindicato Independiente de Docentes","publisher":{"@id":"https:\/\/sidimurcia.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sidimurcia.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sidimurcia.org\/#organization","name":"Sindicato Independiente de Docentes - SIDI","url":"https:\/\/sidimurcia.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sidimurcia.org\/#\/schema\/logo\/image\/","url":"https:\/\/sidimurcia.org\/wp-content\/uploads\/cropped-PARAPESTANAWEB-1.jpg","contentUrl":"https:\/\/sidimurcia.org\/wp-content\/uploads\/cropped-PARAPESTANAWEB-1.jpg","width":512,"height":512,"caption":"Sindicato Independiente de Docentes - SIDI"},"image":{"@id":"https:\/\/sidimurcia.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-es.facebook.com\/sidi.sindicatodedocentes","https:\/\/x.com\/SIDIMURCIA","https:\/\/www.instagram.com\/sidi_murcia\/","https:\/\/www.youtube.com\/channel\/UCwwdL3uFtDKJdbOfmC70wIQ"]},{"@type":"Person","@id":"https:\/\/sidimurcia.org\/#\/schema\/person\/3f3207f88fb267669a31f8f46f76f86c","name":"Jose Luis Torrente","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g","caption":"Jose Luis Torrente"},"url":"https:\/\/sidimurcia.org\/index.php\/author\/joseltorrente\/"}]}},"_links":{"self":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/posts\/7376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/comments?post=7376"}],"version-history":[{"count":0,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/posts\/7376\/revisions"}],"wp:attachment":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/media?parent=7376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/categories?post=7376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/tags?post=7376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}