{"id":9181,"date":"2021-05-20T05:59:51","date_gmt":"2021-05-20T05:59:51","guid":{"rendered":"https:\/\/sidimurcia.org\/?p=9181"},"modified":"2021-06-03T06:29:09","modified_gmt":"2021-06-03T06:29:09","slug":"oposiciones-2021-publicados-miembros-de-tribunal-en-el-borm","status":"publish","type":"post","link":"https:\/\/sidimurcia.org\/index.php\/2021\/05\/20\/oposiciones-2021-publicados-miembros-de-tribunal-en-el-borm\/","title":{"rendered":"OPOSICIONES 2021 &#8211; Publicados miembros de tribunal en el BORM"},"content":{"rendered":"<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/www.borm.es\/services\/anuncio\/ano\/2021\/numero\/3522\/pdf?id=794153\">Orden de 17 de mayo de 2021 por la que se nombran los \u00f3rganos de selecci\u00f3n que han de valorar los procedimientos selectivos convocados por Orden de 25 de enero de 2021, para ingreso, accesos y adquisici\u00f3n de nuevas especialidades, en los cuerpos de Profesores de Ense\u00f1anza Secundaria, Profesores T\u00e9cnicos de Formaci\u00f3n Profesional, Profesores de Escuelas Oficiales de Idiomas, Profesores de M\u00fasica y Artes Esc\u00e9nicas y Profesores de Artes Pl\u00e1sticas y Dise\u00f1o, a celebrar en el a\u00f1o 2021, y se regula la composici\u00f3n de las listas de interinidad para el curso 2021-2022.<\/a>\n<ul>\n<li><a href=\"https:\/\/www.carm.es\/web\/Blob?ARCHIVO=C.E.%20Tribunales.pdf&amp;TABLA=ARCHIVOS&amp;CAMPOCLAVE=IDARCHIVO&amp;VALORCLAVE=170954&amp;CAMPOIMAGEN=ARCHIVO&amp;IDTIPO=60&amp;RASTRO=c798$m3977,69334,69381\">Correcci\u00f3n de errores de la Orden de 17 de mayo de 2021, de la Consejer\u00eda de Educaci\u00f3n y Cultura, por la que se nombran los \u00f3rganos de selecci\u00f3n que han de valorar los procedimientos selectivos convocados por Orden de 25 de enero de 2021, para ingreso, acceso y adquisici\u00f3n de nuevas especialidades en los cuerpos de Profesores de Ense\u00f1anza Secundaria, Profesores T\u00e9cnicos de Formaci\u00f3n Profesional, Profesores de Escuelas Oficiales de Idiomas, Profesores de M\u00fasica y Artes Esc\u00e9nicas y Profesores de Artes Pl\u00e1sticas y Dise\u00f1o, a celebrar en el a\u00f1o 2021, y se regula la composici\u00f3n de las listas de interinidad en estos cuerpos para el curso 2021-2022.<\/a><br \/>\n<a href=\"http:\/\/servicios.educarm.es\/templates\/portal\/ficheros\/websDinamicas\/45\/3927%20Nombr%20preside%20tribunal%20BORM%203-6-21.pdf\">&#8211; Orden de 31 de mayo de 2021, de la Consejer\u00eda de Educaci\u00f3n y Cultura, por la que se nombran nuevos presidentes de los tribunales que han de valorar los procedimientos selectivos convocados por Orden de 25 de enero de 2021, para ingreso, acceso y adquisici\u00f3n de nuevas especialidades en los cuerpos de Profesores de Ense\u00f1anza Secundaria, Profesores T\u00e9cnicos de Formaci\u00f3n Profesional, Profesores de Escuelas Oficiales de Idiomas, Profesores de M\u00fasica y Artes Esc\u00e9nicas y Profesores de Artes Pl\u00e1sticas y Dise\u00f1o, a celebrar en el a\u00f1o 2021, y se regula la composici\u00f3n de las listas de interinidad para el curso 2021-2022<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<div align=\"justify\">\n<div><span style=\"color: #993366;\"><strong>La presentaci\u00f3n de solicitudes de abstenci\u00f3n y recusaci\u00f3n <span style=\"text-decoration: underline;\">ser\u00e1 de cinco d\u00edas<\/span>, <\/strong>contados a partir del d\u00eda siguiente al de la publicaci\u00f3n del nombramiento de los tribunales en el Bolet\u00edn Oficial de la Regi\u00f3n de Murcia. <strong>Plazo d<\/strong><strong>el 21 al 27 de mayo (ambos inclusive)<br \/>\n<\/strong><\/span><\/div>\n<\/div>\n<div><strong>\u00a0<\/strong><\/div>\n<div style=\"text-align: justify;\" align=\"justify\">Las solicitudes deber\u00e1n presentarse de forma telem\u00e1tica, a trav\u00e9s de la sede electr\u00f3nica de la CARM. Se podr\u00e1 acceder al formulario de alegaciones a trav\u00e9s del enlace \u201cRegistro y gu\u00eda de procedimientos y servicios\u201d de la sede electr\u00f3nica. A continuaci\u00f3n, mediante el c\u00f3digo 2496 se acceder\u00e1 al procedimiento \u201cSolicitud de participaci\u00f3n voluntaria o exclusi\u00f3n en los tribunales de los procedimientos selectivos para ingreso en los cuerpos docentes de la Regi\u00f3n de Murcia\u201d.A trav\u00e9s del apartado \u201cPresentaci\u00f3n de solicitudes\u201d se acceder\u00e1 al formulario seleccionando el tr\u00e1mite \u201cSolicitud de abstenci\u00f3n o recusaci\u00f3n de los miembros de los \u00f3rganos de selecci\u00f3n\u201d. En el subapartado \u201cTipo de referencia\u201d deber\u00e1 consignar \u201cReferencia Expediente Origen\u201d y en \u201cReferencia\u201d indique el c\u00f3digo 2496.<br \/>\nSe adjuntar\u00e1, de forma electr\u00f3nica y en formato pdf cuanta documentaci\u00f3n justificativa se considere oportuna en relaci\u00f3n a la alegaci\u00f3n realizada.<\/div>\n<div align=\"justify\"><\/div>\n<div align=\"justify\">\n<ul>\n<li><a href=\"https:\/\/sede.carm.es\/web\/pagina?IDCONTENIDO=2496&amp;IDTIPO=240&amp;RASTRO=c$m40288\">ENLACE SEDE ELECTR\u00d3NICA DE LA CARM (c\u00f3digo 2496 \u00abSolicitud de participaci\u00f3n voluntaria o exclusi\u00f3n en los tribunales de los procedimientos selectivos para ingreso en los cuerpos docentes de la Regi\u00f3n de Murcia) .<\/a><\/li>\n<\/ul>\n<\/div>\n<div><strong>\u00a0<\/strong><\/div>\n<div><strong>Art\u00edculo 22. Abstenci\u00f3n y recusaci\u00f3n<br \/>\n<\/strong><\/p>\n<div align=\"justify\">1. Los miembros de los \u00f3rganos de selecci\u00f3n, tanto presidentes como vocales, deber\u00e1n abstenerse de intervenir, notific\u00e1ndolo a la persona titular de la direcci\u00f3n general competente en materia de recursos humanos, mediante instancia donde se haga constar el n\u00famero de tribunal y la especialidad, con la debida justificaci\u00f3n documental, cuando concurran en ellos alguna de las circunstancias previstas en el art\u00edculo 23 de la Ley 40\/2015, de 1 de octubre, de R\u00e9gimen jur\u00eddico del Sector P\u00fablico <span style=\"color: #800080;\"><strong>(*)<\/strong><\/span>; o si hubiesen realizado tareas de preparaci\u00f3n de aspirantes a pruebas selectivas, para el cuerpo y la especialidad correspondiente, en los cinco a\u00f1os anteriores a la publicaci\u00f3n de esta convocatoria.<\/div>\n<div align=\"justify\">2. El plazo para manifestar la abstenci\u00f3n ser\u00e1 de cinco d\u00edas, contados a partir del d\u00eda siguiente al de la publicaci\u00f3n del nombramiento de los tribunales en el Bolet\u00edn Oficial de la Regi\u00f3n de Murcia. La persona titular de la direcci\u00f3n general competente en materia de recursos humanos de la consejer\u00eda competente en materia de educaci\u00f3n resolver\u00e1 lo procedente.<br \/>\n3. Los aspirantes podr\u00e1n recusar a los miembros del tribunal o de la comisi\u00f3n de selecci\u00f3n de acuerdo con lo previsto en el art\u00edculo 24 de la Ley 40\/2015, de 1 de octubre<\/div>\n<div style=\"padding-left: 40px;\" align=\"justify\"><\/div>\n<div style=\"text-align: justify; padding-left: 40px;\" align=\"justify\"><span style=\"font-size: 14px;\"><strong><span style=\"color: #800080;\">(*)<\/span> Art\u00edculo 23 de la Ley 40\/2015 .\u00a0 Abstenci\u00f3n.<\/strong><\/span><br \/>\n<span style=\"font-size: 14px;\">\u00a0\u00a0\u00a0 1. Las autoridades y el personal al servicio de las Administraciones en quienes se den algunas de las circunstancias se\u00f1aladas en el apartado siguiente se abstendr\u00e1n de intervenir en el procedimiento y lo comunicar\u00e1n a su superior inmediato, quien resolver\u00e1 lo procedente.<\/span><br \/>\n<span style=\"font-size: 14px;\">\u00a0\u00a0\u00a0 2. Son motivos de abstenci\u00f3n los siguientes:<\/span><br \/>\n<span style=\"font-size: 14px;\">\u00a0\u00a0\u00a0 a)\u00a0 Tener\u00a0 inter\u00e9s\u00a0 personal\u00a0 en\u00a0 el\u00a0 asunto\u00a0 de\u00a0 que\u00a0 se\u00a0 trate\u00a0 o\u00a0 en\u00a0 otro\u00a0 en\u00a0 cuya\u00a0 resoluci\u00f3n pudiera\u00a0 influir\u00a0 la\u00a0 de\u00a0 aqu\u00e9l;\u00a0 ser\u00a0 administrador\u00a0 de\u00a0 sociedad\u00a0 o\u00a0 entidad\u00a0 interesada,\u00a0 o\u00a0 tener cuesti\u00f3n litigiosa pendiente con alg\u00fan interesado.<\/span><br \/>\n<span style=\"font-size: 14px;\">\u00a0\u00a0\u00a0 b)\u00a0 Tener\u00a0 un\u00a0 v\u00ednculo\u00a0 matrimonial\u00a0 o\u00a0 situaci\u00f3n\u00a0 de\u00a0 hecho\u00a0 asimilable\u00a0 y\u00a0 el\u00a0 parentesco\u00a0 de consanguinidad dentro del cuarto grado o de afinidad dentro del segundo, con cualquiera delos interesados, con los administradores de entidades o sociedades interesadas y tambi\u00e9n con\u00a0 los\u00a0 asesores,\u00a0 representantes\u00a0 legales\u00a0 o\u00a0 mandatarios\u00a0 que\u00a0 intervengan\u00a0 en\u00a0 el procedimiento, as\u00ed como compartir despacho profesional o estar asociado con \u00e9stos para el asesoramiento, la representaci\u00f3n o el mandato.<\/span><br \/>\n<span style=\"font-size: 14px;\">\u00a0\u00a0\u00a0 c)\u00a0 Tener\u00a0 amistad\u00a0 \u00edntima\u00a0 o\u00a0 enemistad\u00a0 manifiesta\u00a0 con\u00a0 alguna\u00a0 de\u00a0 las\u00a0 personas mencionadas en el apartado anterior.<\/span><br \/>\n<span style=\"font-size: 14px;\">\u00a0\u00a0\u00a0 d) Haber intervenido como perito o como testigo en el procedimiento de que se trate.<\/span><br \/>\n<span style=\"font-size: 14px;\">\u00a0\u00a0\u00a0 e) Tener relaci\u00f3n de servicio con persona natural o jur\u00eddica interesada directamente en el asunto, o haberle prestado en los dos \u00faltimos a\u00f1os servicios profesionales de cualquier tipo y en cualquier circunstancia o lugar.<\/span><br \/>\n<span style=\"font-size: 14px;\">\u00a0\u00a0\u00a0 3.\u00a0 Los\u00a0 \u00f3rganos\u00a0 jer\u00e1rquicamente\u00a0 superiores\u00a0 a\u00a0 quien\u00a0 se\u00a0 encuentre\u00a0 en alguna\u00a0 de\u00a0 las circunstancias se\u00f1aladas en el punto anterior podr\u00e1n ordenarle que se abstengan de toda intervenci\u00f3n en el expediente.<\/span><br \/>\n<span style=\"font-size: 14px;\">\u00a0\u00a0\u00a0 4. La actuaci\u00f3n de autoridades y personal al servicio de las Administraciones P\u00fablicas en los que concurran motivos de abstenci\u00f3n no implicar\u00e1, necesariamente, y en todo caso, la invalidez de los actos en que hayan intervenido.<\/span><br \/>\n<span style=\"font-size: 14px;\">\u00a0\u00a0\u00a0 5. La no abstenci\u00f3n en los casos en que concurra alguna de esas circunstancias dar\u00e1 lugar a la responsabilidad que proceda.<\/span><\/div>\n<div align=\"justify\"><\/div>\n<div style=\"text-align: justify;\" align=\"justify\"><strong>Art\u00edculo 23. Convocatoria y acto de constituci\u00f3n de tribunales y comisiones de selecci\u00f3n<\/strong><br \/>\n1. Previa convocatoria de los presidentes, se constituir\u00e1n los tribunales y las comisiones de selecci\u00f3n.<br \/>\n2. Para el acto de constituci\u00f3n de los tribunales, los presidentes de cada tribunal convocar\u00e1n, con al menos dos d\u00edas de antelaci\u00f3n, a los vocales, titulares y suplentes, y en su caso, al presidente suplente.<br \/>\n3. Para el acto de constituci\u00f3n de las comisiones de selecci\u00f3n, los presidentes de cada comisi\u00f3n convocar\u00e1n, con al menos dos d\u00edas de antelaci\u00f3n a los miembros de la misma, titulares y suplentes.<br \/>\n4. Los presidentes solicitar\u00e1n de los miembros de los \u00f3rganos de selecci\u00f3n declaraci\u00f3n expresa de no hallarse incursos en las circunstancias previstas en el art\u00edculo 22.<br \/>\n5.\u00a0 En\u00a0 el\u00a0 acto\u00a0 de\u00a0 constituci\u00f3n\u00a0 deben\u00a0 tener\u00a0 en\u00a0 cuenta\u00a0 las\u00a0 siguientes circunstancias:<br \/>\na) La exenci\u00f3n de participaci\u00f3n en los tribunales por enfermedad s\u00f3lo ser\u00e1 efectiva mediante la concesi\u00f3n de la licencia por enfermedad o estar en posesi\u00f3n del correspondiente \u00abcertificado de exenci\u00f3n\u00bb expedido por el servicio competente en materia de prevenci\u00f3n de riesgos laborales de la consejer\u00eda competente en materia de educaci\u00f3n.<br \/>\nLa propuesta de baja por enfermedad ocasional, expedida por cualquier facultativo, no exime de la obligaci\u00f3n de participar en los tribunales. El funcionario afectado por dicha situaci\u00f3n comunicar\u00e1 de inmediato tal hecho mediante escrito dirigido a la direcci\u00f3n general competente en materia de recursos humanos, indicando su disponibilidad a constituirse y participar en el tribunal. Dicho escrito se presentar\u00e1 preferentemente, en la Oficina Corporativa de Atenci\u00f3n al Ciudadano de la consejer\u00eda competente en materia de educaci\u00f3n, pudiendo, adem\u00e1s, utilizarse cualquiera de los medios previstos en el art\u00edculo 16.4 de la Ley 39\/2015, de 1 de octubre.<br \/>\nEn el supuesto de ausencia por enfermedad grave o de larga duraci\u00f3n, la Unidad de Inspecci\u00f3n M\u00e9dica de esta consejer\u00eda expedir\u00e1 la certificaci\u00f3n de la exenci\u00f3n correspondiente y la remitir\u00e1 a la direcci\u00f3n general competente en materia de recursos humanos, que lo notificar\u00e1 al presidente del tribunal.<br \/>\nb)\u00a0 Aquellos\u00a0 funcionarios\u00a0 que\u00a0 en\u00a0 el\u00a0 acto\u00a0 de\u00a0 constituci\u00f3n\u00a0 del\u00a0 tribunal manifiesten haber realizado tareas de preparaci\u00f3n de aspirantes a pruebas selectivas, para el cuerpo y la especialidad correspondiente, en los cinco a\u00f1os anteriores a la publicaci\u00f3n de esta convocatoria, deber\u00e1n aportar al presidente del tribunal que les corresponda, de manera inexcusable para ser eximidos de su participaci\u00f3n, uno de los siguientes documentos:<br \/>\n&#8211; Certificaci\u00f3n de la academia o centro docente donde las haya realizado.<br \/>\n&#8211; Certificado de alta en el Impuesto de Actividades Econ\u00f3micas, en los casos que fuese necesario.<br \/>\nc) A los funcionarios que, en el acto de constituci\u00f3n del tribunal, o cuando tengan\u00a0 conocimiento\u00a0 de\u00a0 ello,\u00a0 manifiesten\u00a0 tener\u00a0 parentesco, debidamente justificado,\u00a0 de\u00a0 consanguinidad\u00a0 hasta\u00a0 el\u00a0 cuarto\u00a0 grado\u00a0 o\u00a0 de\u00a0 afinidad\u00a0 hasta el segundo grado, con cualquiera de los aspirantes de su especialidad, se les conceder\u00e1 la abstenci\u00f3n de intervenir en dicha especialidad. La consejer\u00eda competente en materia de educaci\u00f3n podr\u00e1 nombrar a estos funcionarios como miembros de tribunales de otra especialidad.<br \/>\nd) En el caso de inasistencia al acto de constituci\u00f3n de alguno de los convocados por los motivos anteriormente descritos o por cualquier otro, sin que haya existido justificaci\u00f3n previa al presidente del tribunal mediante correo electr\u00f3nico oficial proporcionado al efecto o sin que haya autorizaci\u00f3n expresa de la direcci\u00f3n general competente en materia de recursos humanos, no se constituir\u00e1 el tribunal, volviendo a convocarse en el plazo de veinticuatro horas, ycomunicando inmediatamente el presidente del tribunal el incidente a la direcci\u00f3n general competente en materia de recursos humanos para que adopte las medidas disciplinarias que, en su caso, correspondan.<br \/>\ne) La inasistencia injustificada de los miembros de los tribunales a las distintas sesiones y actos del procedimiento, incluido el acto de constituci\u00f3n, dar\u00e1 lugar a la exigencia de la responsabilidad que corresponda.<\/div>\n<div align=\"justify\"><\/div>\n<div style=\"text-align: justify;\" align=\"justify\"><strong>Art\u00edculo 24. Suplencia de los miembros de los tribunales<\/strong><br \/>\n1. El orden de actuaci\u00f3n de los vocales suplentes ser\u00e1 en primer lugar el vocal suplente n\u00famero uno del tribunal y, en su defecto, sucesivamente el resto de los vocales suplentes, por el orden en que figuran dispuestos en la orden de nombramiento, salvo que el tribunal determine otro procedimiento, por unanimidad de los presentes en el acto de constituci\u00f3n.<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Orden de 17 de mayo de 2021 por la que se nombran los \u00f3rganos de selecci\u00f3n que han de valorar &#8230; <a title=\"OPOSICIONES 2021 &#8211; Publicados miembros de tribunal en el BORM\" class=\"read-more\" href=\"https:\/\/sidimurcia.org\/index.php\/2021\/05\/20\/oposiciones-2021-publicados-miembros-de-tribunal-en-el-borm\/\" aria-label=\"Leer m\u00e1s sobre OPOSICIONES 2021 &#8211; Publicados miembros de tribunal en el BORM\">Leer mas<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43,85],"tags":[],"class_list":["post-9181","post","type-post","status-publish","format-standard","hentry","category-oposiciones","category-oposiciones-2021"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>OPOSICIONES 2021 - Publicados miembros de tribunal en el BORM - SIDI<\/title>\n<meta name=\"description\" content=\"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sidimurcia.org\/index.php\/2021\/05\/20\/oposiciones-2021-publicados-miembros-de-tribunal-en-el-borm\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OPOSICIONES 2021 - Publicados miembros de tribunal en el BORM - SIDI\" \/>\n<meta property=\"og:description\" content=\"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sidimurcia.org\/index.php\/2021\/05\/20\/oposiciones-2021-publicados-miembros-de-tribunal-en-el-borm\/\" \/>\n<meta property=\"og:site_name\" content=\"SIDI\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-es.facebook.com\/sidi.sindicatodedocentes\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-20T05:59:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-03T06:29:09+00:00\" \/>\n<meta name=\"author\" content=\"Jose Luis Torrente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SIDIMURCIA\" \/>\n<meta name=\"twitter:site\" content=\"@SIDIMURCIA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jose Luis Torrente\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2021\\\/05\\\/20\\\/oposiciones-2021-publicados-miembros-de-tribunal-en-el-borm\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2021\\\/05\\\/20\\\/oposiciones-2021-publicados-miembros-de-tribunal-en-el-borm\\\/\"},\"author\":{\"name\":\"Jose Luis Torrente\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/person\\\/3f3207f88fb267669a31f8f46f76f86c\"},\"headline\":\"OPOSICIONES 2021 &#8211; Publicados miembros de tribunal en el BORM\",\"datePublished\":\"2021-05-20T05:59:51+00:00\",\"dateModified\":\"2021-06-03T06:29:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2021\\\/05\\\/20\\\/oposiciones-2021-publicados-miembros-de-tribunal-en-el-borm\\\/\"},\"wordCount\":1883,\"publisher\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#organization\"},\"articleSection\":[\"Oposiciones\",\"Oposiciones 2021\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2021\\\/05\\\/20\\\/oposiciones-2021-publicados-miembros-de-tribunal-en-el-borm\\\/\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2021\\\/05\\\/20\\\/oposiciones-2021-publicados-miembros-de-tribunal-en-el-borm\\\/\",\"name\":\"OPOSICIONES 2021 - Publicados miembros de tribunal en el BORM - SIDI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#website\"},\"datePublished\":\"2021-05-20T05:59:51+00:00\",\"dateModified\":\"2021-06-03T06:29:09+00:00\",\"description\":\"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\\\/mes. Defendemos la educaci\u00f3n p\u00fablica.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2021\\\/05\\\/20\\\/oposiciones-2021-publicados-miembros-de-tribunal-en-el-borm\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2021\\\/05\\\/20\\\/oposiciones-2021-publicados-miembros-de-tribunal-en-el-borm\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2021\\\/05\\\/20\\\/oposiciones-2021-publicados-miembros-de-tribunal-en-el-borm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sidimurcia.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OPOSICIONES 2021 &#8211; Publicados miembros de tribunal en el BORM\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#website\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/\",\"name\":\"SIDI\",\"description\":\"Sindicato Independiente de Docentes\",\"publisher\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sidimurcia.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#organization\",\"name\":\"Sindicato Independiente de Docentes - SIDI\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/wp-content\\\/uploads\\\/cropped-PARAPESTANAWEB-1.jpg\",\"contentUrl\":\"https:\\\/\\\/sidimurcia.org\\\/wp-content\\\/uploads\\\/cropped-PARAPESTANAWEB-1.jpg\",\"width\":512,\"height\":512,\"caption\":\"Sindicato Independiente de Docentes - SIDI\"},\"image\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-es.facebook.com\\\/sidi.sindicatodedocentes\",\"https:\\\/\\\/x.com\\\/SIDIMURCIA\",\"https:\\\/\\\/www.instagram.com\\\/sidi_murcia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCwwdL3uFtDKJdbOfmC70wIQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/person\\\/3f3207f88fb267669a31f8f46f76f86c\",\"name\":\"Jose Luis Torrente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g\",\"caption\":\"Jose Luis Torrente\"},\"url\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/author\\\/joseltorrente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OPOSICIONES 2021 - Publicados miembros de tribunal en el BORM - SIDI","description":"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sidimurcia.org\/index.php\/2021\/05\/20\/oposiciones-2021-publicados-miembros-de-tribunal-en-el-borm\/","og_locale":"es_ES","og_type":"article","og_title":"OPOSICIONES 2021 - Publicados miembros de tribunal en el BORM - SIDI","og_description":"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.","og_url":"https:\/\/sidimurcia.org\/index.php\/2021\/05\/20\/oposiciones-2021-publicados-miembros-de-tribunal-en-el-borm\/","og_site_name":"SIDI","article_publisher":"https:\/\/es-es.facebook.com\/sidi.sindicatodedocentes","article_published_time":"2021-05-20T05:59:51+00:00","article_modified_time":"2021-06-03T06:29:09+00:00","author":"Jose Luis Torrente","twitter_card":"summary_large_image","twitter_creator":"@SIDIMURCIA","twitter_site":"@SIDIMURCIA","twitter_misc":{"Escrito por":"Jose Luis Torrente","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sidimurcia.org\/index.php\/2021\/05\/20\/oposiciones-2021-publicados-miembros-de-tribunal-en-el-borm\/#article","isPartOf":{"@id":"https:\/\/sidimurcia.org\/index.php\/2021\/05\/20\/oposiciones-2021-publicados-miembros-de-tribunal-en-el-borm\/"},"author":{"name":"Jose Luis Torrente","@id":"https:\/\/sidimurcia.org\/#\/schema\/person\/3f3207f88fb267669a31f8f46f76f86c"},"headline":"OPOSICIONES 2021 &#8211; Publicados miembros de tribunal en el BORM","datePublished":"2021-05-20T05:59:51+00:00","dateModified":"2021-06-03T06:29:09+00:00","mainEntityOfPage":{"@id":"https:\/\/sidimurcia.org\/index.php\/2021\/05\/20\/oposiciones-2021-publicados-miembros-de-tribunal-en-el-borm\/"},"wordCount":1883,"publisher":{"@id":"https:\/\/sidimurcia.org\/#organization"},"articleSection":["Oposiciones","Oposiciones 2021"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/sidimurcia.org\/index.php\/2021\/05\/20\/oposiciones-2021-publicados-miembros-de-tribunal-en-el-borm\/","url":"https:\/\/sidimurcia.org\/index.php\/2021\/05\/20\/oposiciones-2021-publicados-miembros-de-tribunal-en-el-borm\/","name":"OPOSICIONES 2021 - Publicados miembros de tribunal en el BORM - SIDI","isPartOf":{"@id":"https:\/\/sidimurcia.org\/#website"},"datePublished":"2021-05-20T05:59:51+00:00","dateModified":"2021-06-03T06:29:09+00:00","description":"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.","breadcrumb":{"@id":"https:\/\/sidimurcia.org\/index.php\/2021\/05\/20\/oposiciones-2021-publicados-miembros-de-tribunal-en-el-borm\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sidimurcia.org\/index.php\/2021\/05\/20\/oposiciones-2021-publicados-miembros-de-tribunal-en-el-borm\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sidimurcia.org\/index.php\/2021\/05\/20\/oposiciones-2021-publicados-miembros-de-tribunal-en-el-borm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sidimurcia.org\/"},{"@type":"ListItem","position":2,"name":"OPOSICIONES 2021 &#8211; Publicados miembros de tribunal en el BORM"}]},{"@type":"WebSite","@id":"https:\/\/sidimurcia.org\/#website","url":"https:\/\/sidimurcia.org\/","name":"SIDI","description":"Sindicato Independiente de Docentes","publisher":{"@id":"https:\/\/sidimurcia.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sidimurcia.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sidimurcia.org\/#organization","name":"Sindicato Independiente de Docentes - SIDI","url":"https:\/\/sidimurcia.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sidimurcia.org\/#\/schema\/logo\/image\/","url":"https:\/\/sidimurcia.org\/wp-content\/uploads\/cropped-PARAPESTANAWEB-1.jpg","contentUrl":"https:\/\/sidimurcia.org\/wp-content\/uploads\/cropped-PARAPESTANAWEB-1.jpg","width":512,"height":512,"caption":"Sindicato Independiente de Docentes - SIDI"},"image":{"@id":"https:\/\/sidimurcia.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-es.facebook.com\/sidi.sindicatodedocentes","https:\/\/x.com\/SIDIMURCIA","https:\/\/www.instagram.com\/sidi_murcia\/","https:\/\/www.youtube.com\/channel\/UCwwdL3uFtDKJdbOfmC70wIQ"]},{"@type":"Person","@id":"https:\/\/sidimurcia.org\/#\/schema\/person\/3f3207f88fb267669a31f8f46f76f86c","name":"Jose Luis Torrente","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g","caption":"Jose Luis Torrente"},"url":"https:\/\/sidimurcia.org\/index.php\/author\/joseltorrente\/"}]}},"_links":{"self":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/posts\/9181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/comments?post=9181"}],"version-history":[{"count":0,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/posts\/9181\/revisions"}],"wp:attachment":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/media?parent=9181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/categories?post=9181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/tags?post=9181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}