{"id":9678,"date":"2021-06-23T16:45:06","date_gmt":"2021-06-23T16:45:06","guid":{"rendered":"https:\/\/sidimurcia.org\/?p=9678"},"modified":"2021-06-23T17:29:49","modified_gmt":"2021-06-23T17:29:49","slug":"oposiciones-2021-instrucciones-al-tribunal-no-7-de-la-especialidad-de-pga-sobre-la-celebracion-de-la-primera-prueba","status":"publish","type":"post","link":"https:\/\/sidimurcia.org\/index.php\/2021\/06\/23\/oposiciones-2021-instrucciones-al-tribunal-no-7-de-la-especialidad-de-pga-sobre-la-celebracion-de-la-primera-prueba\/","title":{"rendered":"OPOSICIONES 2021: Instrucciones al tribunal n\u00ba 7 de la especialidad de PGA sobre la celebraci\u00f3n de la Primera Prueba"},"content":{"rendered":"<ul>\n<li style=\"text-align: justify;\"><a title=\"Resoluci\u00f3n de la Direcci\u00f3n General de Planificaci\u00f3n Educativa y Recursos Humanos por la que se dictan instrucciones al tribunal n\u00ba 7 de la especialidad de Procesos de Gesti\u00f3n Administrativa sobre la celebraci\u00f3n de la Primera Prueba\" href=\"https:\/\/www.carm.es\/web\/Blob?ARCHIVO=Resoluci%C3%B3n%20PGA%20%28COPIA%29.pdf&amp;TABLA=ARCHIVOS&amp;CAMPOCLAVE=IDARCHIVO&amp;VALORCLAVE=171648&amp;CAMPOIMAGEN=ARCHIVO&amp;IDTIPO=60&amp;RASTRO=c77$m22725,22759,4254\">Resoluci\u00f3n de la Direcci\u00f3n General de Planificaci\u00f3n Educativa y Recursos Humanos por la que se dictan instrucciones al tribunal n\u00ba 7 de la especialidad de Procesos de Gesti\u00f3n Administrativa sobre la celebraci\u00f3n de la Primera Prueba<\/a><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Habiendo sido informada esta Direcci\u00f3n General por el presidente de la comisi\u00f3n de selecci\u00f3n de la especialidad de Procesos de Gesti\u00f3n Administrativa sobre la disparidad de tratamiento en el tribunal 7 en cuanto al uso de calculadoras en las pruebas celebradas el d\u00eda 19 de junio en la especialidad de Procesos de Gesti\u00f3n Administrativa, vistos los recursos presentados, con objeto de garantizar la igualdad de oportunidades y la seguridad jur\u00eddica de todos los participantes en el mismo,<\/p>\n<p style=\"text-align: justify;\">RESUELVO<\/p>\n<p style=\"text-align: justify;\">1. Los opositores del tribunal 7 de la especialidad de Procesos de Gesti\u00f3n Administrativa que se vieron afectados por la disparidad en el uso de calculadoras en la parte A de la primera prueba celebrada el d\u00eda 19 de junio, podr\u00e1n concurrir, si as\u00ed lo desean, a una prueba de similares caracter\u00edsticas a la celebrada dicho d\u00eda, con las mismas condiciones, garant\u00edas y criterios de evaluaci\u00f3n aplicados al resto de opositores de la especialidad.<br \/>\n2. <strong>Dicha prueba se celebrar\u00e1 el d\u00eda 28 de junio de 2021 a las 9:00 horas en el IES Alquer\u00edas (C\/ Francisco Jos\u00e9 Vicente Ortega, 30580 Alquer\u00edas, Murcia). Quienes decidan no concurrir seguir\u00e1n en el procedimiento con las pruebas realizadas hasta el momento.<\/strong><br \/>\n3. La concurrencia a dicha prueba supondr\u00e1 la anulaci\u00f3n autom\u00e1tica del ejercicio anterior (parte A) y su sustituci\u00f3n por el \u00faltimo realizado. Ser\u00e1 requisito para concurrir a la misma el haberse presentado a la parte A de la primera prueba celebrada el 19 de junio.<br \/>\n4. Se permitir\u00e1 el uso de calculadora no programable ni gr\u00e1fica, que no incluya funciones, ni posibilidad de almacenar caracteres alfanum\u00e9ricos, ni transmisi\u00f3n de datos. No obstante, por razones de equidad, de acuerdo con lo permitido en el resto de tribunales en la prueba del d\u00eda 19 de junio, ser\u00e1n v\u00e1lidas las calculadoras con funciones trigonom\u00e9tricas.<br \/>\n5. La publicaci\u00f3n de notas se har\u00e1 teniendo en cuenta esta circunstancia en los casamientos de cabeceras, dejando constancia en el acta de los opositores que han optado por concurrir a la prueba descrita en el punto 1.<\/p>\n<p>EL DIRECTOR GENERAL DE PLANIFICACI\u00d3N EDUCATIVA Y RECURSOS HUMANOS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resoluci\u00f3n de la Direcci\u00f3n General de Planificaci\u00f3n Educativa y Recursos Humanos por la que se dictan instrucciones al tribunal n\u00ba &#8230; <a title=\"OPOSICIONES 2021: Instrucciones al tribunal n\u00ba 7 de la especialidad de PGA sobre la celebraci\u00f3n de la Primera Prueba\" class=\"read-more\" href=\"https:\/\/sidimurcia.org\/index.php\/2021\/06\/23\/oposiciones-2021-instrucciones-al-tribunal-no-7-de-la-especialidad-de-pga-sobre-la-celebracion-de-la-primera-prueba\/\" aria-label=\"Leer m\u00e1s sobre OPOSICIONES 2021: Instrucciones al tribunal n\u00ba 7 de la especialidad de PGA sobre la celebraci\u00f3n de la Primera Prueba\">Leer mas<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43,85],"tags":[],"class_list":["post-9678","post","type-post","status-publish","format-standard","hentry","category-oposiciones","category-oposiciones-2021"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>OPOSICIONES 2021: Instrucciones al tribunal n\u00ba 7 de la especialidad de PGA sobre la celebraci\u00f3n de la Primera Prueba - SIDI<\/title>\n<meta name=\"description\" content=\"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sidimurcia.org\/index.php\/2021\/06\/23\/oposiciones-2021-instrucciones-al-tribunal-no-7-de-la-especialidad-de-pga-sobre-la-celebracion-de-la-primera-prueba\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OPOSICIONES 2021: Instrucciones al tribunal n\u00ba 7 de la especialidad de PGA sobre la celebraci\u00f3n de la Primera Prueba - SIDI\" \/>\n<meta property=\"og:description\" content=\"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sidimurcia.org\/index.php\/2021\/06\/23\/oposiciones-2021-instrucciones-al-tribunal-no-7-de-la-especialidad-de-pga-sobre-la-celebracion-de-la-primera-prueba\/\" \/>\n<meta property=\"og:site_name\" content=\"SIDI\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-es.facebook.com\/sidi.sindicatodedocentes\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-23T16:45:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-23T17:29:49+00:00\" \/>\n<meta name=\"author\" content=\"Jose Luis Torrente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SIDIMURCIA\" \/>\n<meta name=\"twitter:site\" content=\"@SIDIMURCIA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jose Luis Torrente\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2021\\\/06\\\/23\\\/oposiciones-2021-instrucciones-al-tribunal-no-7-de-la-especialidad-de-pga-sobre-la-celebracion-de-la-primera-prueba\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2021\\\/06\\\/23\\\/oposiciones-2021-instrucciones-al-tribunal-no-7-de-la-especialidad-de-pga-sobre-la-celebracion-de-la-primera-prueba\\\/\"},\"author\":{\"name\":\"Jose Luis Torrente\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/person\\\/3f3207f88fb267669a31f8f46f76f86c\"},\"headline\":\"OPOSICIONES 2021: Instrucciones al tribunal n\u00ba 7 de la especialidad de PGA sobre la celebraci\u00f3n de la Primera Prueba\",\"datePublished\":\"2021-06-23T16:45:06+00:00\",\"dateModified\":\"2021-06-23T17:29:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2021\\\/06\\\/23\\\/oposiciones-2021-instrucciones-al-tribunal-no-7-de-la-especialidad-de-pga-sobre-la-celebracion-de-la-primera-prueba\\\/\"},\"wordCount\":415,\"publisher\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#organization\"},\"articleSection\":[\"Oposiciones\",\"Oposiciones 2021\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2021\\\/06\\\/23\\\/oposiciones-2021-instrucciones-al-tribunal-no-7-de-la-especialidad-de-pga-sobre-la-celebracion-de-la-primera-prueba\\\/\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2021\\\/06\\\/23\\\/oposiciones-2021-instrucciones-al-tribunal-no-7-de-la-especialidad-de-pga-sobre-la-celebracion-de-la-primera-prueba\\\/\",\"name\":\"OPOSICIONES 2021: Instrucciones al tribunal n\u00ba 7 de la especialidad de PGA sobre la celebraci\u00f3n de la Primera Prueba - SIDI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#website\"},\"datePublished\":\"2021-06-23T16:45:06+00:00\",\"dateModified\":\"2021-06-23T17:29:49+00:00\",\"description\":\"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\\\/mes. Defendemos la educaci\u00f3n p\u00fablica.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2021\\\/06\\\/23\\\/oposiciones-2021-instrucciones-al-tribunal-no-7-de-la-especialidad-de-pga-sobre-la-celebracion-de-la-primera-prueba\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2021\\\/06\\\/23\\\/oposiciones-2021-instrucciones-al-tribunal-no-7-de-la-especialidad-de-pga-sobre-la-celebracion-de-la-primera-prueba\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/2021\\\/06\\\/23\\\/oposiciones-2021-instrucciones-al-tribunal-no-7-de-la-especialidad-de-pga-sobre-la-celebracion-de-la-primera-prueba\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sidimurcia.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OPOSICIONES 2021: Instrucciones al tribunal n\u00ba 7 de la especialidad de PGA sobre la celebraci\u00f3n de la Primera Prueba\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#website\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/\",\"name\":\"SIDI\",\"description\":\"Sindicato Independiente de Docentes\",\"publisher\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sidimurcia.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#organization\",\"name\":\"Sindicato Independiente de Docentes - SIDI\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sidimurcia.org\\\/wp-content\\\/uploads\\\/cropped-PARAPESTANAWEB-1.jpg\",\"contentUrl\":\"https:\\\/\\\/sidimurcia.org\\\/wp-content\\\/uploads\\\/cropped-PARAPESTANAWEB-1.jpg\",\"width\":512,\"height\":512,\"caption\":\"Sindicato Independiente de Docentes - SIDI\"},\"image\":{\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-es.facebook.com\\\/sidi.sindicatodedocentes\",\"https:\\\/\\\/x.com\\\/SIDIMURCIA\",\"https:\\\/\\\/www.instagram.com\\\/sidi_murcia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCwwdL3uFtDKJdbOfmC70wIQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sidimurcia.org\\\/#\\\/schema\\\/person\\\/3f3207f88fb267669a31f8f46f76f86c\",\"name\":\"Jose Luis Torrente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g\",\"caption\":\"Jose Luis Torrente\"},\"url\":\"https:\\\/\\\/sidimurcia.org\\\/index.php\\\/author\\\/joseltorrente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OPOSICIONES 2021: Instrucciones al tribunal n\u00ba 7 de la especialidad de PGA sobre la celebraci\u00f3n de la Primera Prueba - SIDI","description":"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sidimurcia.org\/index.php\/2021\/06\/23\/oposiciones-2021-instrucciones-al-tribunal-no-7-de-la-especialidad-de-pga-sobre-la-celebracion-de-la-primera-prueba\/","og_locale":"es_ES","og_type":"article","og_title":"OPOSICIONES 2021: Instrucciones al tribunal n\u00ba 7 de la especialidad de PGA sobre la celebraci\u00f3n de la Primera Prueba - SIDI","og_description":"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.","og_url":"https:\/\/sidimurcia.org\/index.php\/2021\/06\/23\/oposiciones-2021-instrucciones-al-tribunal-no-7-de-la-especialidad-de-pga-sobre-la-celebracion-de-la-primera-prueba\/","og_site_name":"SIDI","article_publisher":"https:\/\/es-es.facebook.com\/sidi.sindicatodedocentes","article_published_time":"2021-06-23T16:45:06+00:00","article_modified_time":"2021-06-23T17:29:49+00:00","author":"Jose Luis Torrente","twitter_card":"summary_large_image","twitter_creator":"@SIDIMURCIA","twitter_site":"@SIDIMURCIA","twitter_misc":{"Escrito por":"Jose Luis Torrente","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sidimurcia.org\/index.php\/2021\/06\/23\/oposiciones-2021-instrucciones-al-tribunal-no-7-de-la-especialidad-de-pga-sobre-la-celebracion-de-la-primera-prueba\/#article","isPartOf":{"@id":"https:\/\/sidimurcia.org\/index.php\/2021\/06\/23\/oposiciones-2021-instrucciones-al-tribunal-no-7-de-la-especialidad-de-pga-sobre-la-celebracion-de-la-primera-prueba\/"},"author":{"name":"Jose Luis Torrente","@id":"https:\/\/sidimurcia.org\/#\/schema\/person\/3f3207f88fb267669a31f8f46f76f86c"},"headline":"OPOSICIONES 2021: Instrucciones al tribunal n\u00ba 7 de la especialidad de PGA sobre la celebraci\u00f3n de la Primera Prueba","datePublished":"2021-06-23T16:45:06+00:00","dateModified":"2021-06-23T17:29:49+00:00","mainEntityOfPage":{"@id":"https:\/\/sidimurcia.org\/index.php\/2021\/06\/23\/oposiciones-2021-instrucciones-al-tribunal-no-7-de-la-especialidad-de-pga-sobre-la-celebracion-de-la-primera-prueba\/"},"wordCount":415,"publisher":{"@id":"https:\/\/sidimurcia.org\/#organization"},"articleSection":["Oposiciones","Oposiciones 2021"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/sidimurcia.org\/index.php\/2021\/06\/23\/oposiciones-2021-instrucciones-al-tribunal-no-7-de-la-especialidad-de-pga-sobre-la-celebracion-de-la-primera-prueba\/","url":"https:\/\/sidimurcia.org\/index.php\/2021\/06\/23\/oposiciones-2021-instrucciones-al-tribunal-no-7-de-la-especialidad-de-pga-sobre-la-celebracion-de-la-primera-prueba\/","name":"OPOSICIONES 2021: Instrucciones al tribunal n\u00ba 7 de la especialidad de PGA sobre la celebraci\u00f3n de la Primera Prueba - SIDI","isPartOf":{"@id":"https:\/\/sidimurcia.org\/#website"},"datePublished":"2021-06-23T16:45:06+00:00","dateModified":"2021-06-23T17:29:49+00:00","description":"Sindicato Independiente de Docentes. Funcionarios e Interinos. Afiliaci\u00f3n 1eur\/mes. Defendemos la educaci\u00f3n p\u00fablica.","breadcrumb":{"@id":"https:\/\/sidimurcia.org\/index.php\/2021\/06\/23\/oposiciones-2021-instrucciones-al-tribunal-no-7-de-la-especialidad-de-pga-sobre-la-celebracion-de-la-primera-prueba\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sidimurcia.org\/index.php\/2021\/06\/23\/oposiciones-2021-instrucciones-al-tribunal-no-7-de-la-especialidad-de-pga-sobre-la-celebracion-de-la-primera-prueba\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sidimurcia.org\/index.php\/2021\/06\/23\/oposiciones-2021-instrucciones-al-tribunal-no-7-de-la-especialidad-de-pga-sobre-la-celebracion-de-la-primera-prueba\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sidimurcia.org\/"},{"@type":"ListItem","position":2,"name":"OPOSICIONES 2021: Instrucciones al tribunal n\u00ba 7 de la especialidad de PGA sobre la celebraci\u00f3n de la Primera Prueba"}]},{"@type":"WebSite","@id":"https:\/\/sidimurcia.org\/#website","url":"https:\/\/sidimurcia.org\/","name":"SIDI","description":"Sindicato Independiente de Docentes","publisher":{"@id":"https:\/\/sidimurcia.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sidimurcia.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sidimurcia.org\/#organization","name":"Sindicato Independiente de Docentes - SIDI","url":"https:\/\/sidimurcia.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sidimurcia.org\/#\/schema\/logo\/image\/","url":"https:\/\/sidimurcia.org\/wp-content\/uploads\/cropped-PARAPESTANAWEB-1.jpg","contentUrl":"https:\/\/sidimurcia.org\/wp-content\/uploads\/cropped-PARAPESTANAWEB-1.jpg","width":512,"height":512,"caption":"Sindicato Independiente de Docentes - SIDI"},"image":{"@id":"https:\/\/sidimurcia.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-es.facebook.com\/sidi.sindicatodedocentes","https:\/\/x.com\/SIDIMURCIA","https:\/\/www.instagram.com\/sidi_murcia\/","https:\/\/www.youtube.com\/channel\/UCwwdL3uFtDKJdbOfmC70wIQ"]},{"@type":"Person","@id":"https:\/\/sidimurcia.org\/#\/schema\/person\/3f3207f88fb267669a31f8f46f76f86c","name":"Jose Luis Torrente","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ac4c0d28cf03f62a37681e633afaf3faec3a7bd495cdfb9b6a7ec6cf281b29c?s=96&d=mm&r=g","caption":"Jose Luis Torrente"},"url":"https:\/\/sidimurcia.org\/index.php\/author\/joseltorrente\/"}]}},"_links":{"self":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/posts\/9678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/comments?post=9678"}],"version-history":[{"count":0,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/posts\/9678\/revisions"}],"wp:attachment":[{"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/media?parent=9678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/categories?post=9678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sidimurcia.org\/index.php\/wp-json\/wp\/v2\/tags?post=9678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}